{"id":3484,"count":2,"description":"","link":"https:\/\/salonforall.es\/pt\/equipamiento-de-peluqueria\/mobiliario-de-peluqueria\/sillones-y-lavabos-de-peluqueria\/prato\/","name":"Prato","slug":"prato","taxonomy":"product_cat","parent":98,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prato - Salon For ALL Espa\u00f1a<\/title>\n<meta name=\"description\" content=\"Compra tu Prato en Salon For ALL Espa\u00f1a. El mayorista en Espa\u00f1a y Portugal para cada sal\u00f3n. M\u00e1s de 10.000 productos online.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/salonforall.es\/pt\/equipamento-de-cabeleireiro\/mobiliario-de-cabeleireiro\/cadeiras-de-cabeleireiro-e-lavatorios\/prato\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prato - Salon For ALL Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"Compra tu Prato en Salon For ALL Espa\u00f1a. El mayorista en Espa\u00f1a y Portugal para cada sal\u00f3n. M\u00e1s de 10.000 productos online.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/salonforall.es\/pt\/equipamento-de-cabeleireiro\/mobiliario-de-cabeleireiro\/cadeiras-de-cabeleireiro-e-lavatorios\/prato\/\" \/>\n<meta property=\"og:site_name\" content=\"Salon For ALL Espa\u00f1a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/equipamiento-de-peluqueria\\\/mobiliario-de-peluqueria\\\/sillones-y-lavabos-de-peluqueria\\\/prato\\\/\",\"url\":\"https:\\\/\\\/salonforall.es\\\/equipamiento-de-peluqueria\\\/mobiliario-de-peluqueria\\\/sillones-y-lavabos-de-peluqueria\\\/prato\\\/\",\"name\":\"Prato - Salon For ALL Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/salonforall.es\\\/#website\"},\"description\":\"Compra tu Prato en Salon For ALL Espa\u00f1a. El mayorista en Espa\u00f1a y Portugal para cada sal\u00f3n. M\u00e1s de 10.000 productos online.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/salonforall.es\\\/equipamiento-de-peluqueria\\\/mobiliario-de-peluqueria\\\/sillones-y-lavabos-de-peluqueria\\\/prato\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/equipamiento-de-peluqueria\\\/mobiliario-de-peluqueria\\\/sillones-y-lavabos-de-peluqueria\\\/prato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/salonforall.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Equipamiento de peluquer\u00eda\",\"item\":\"https:\\\/\\\/salonforall.es\\\/equipamiento-de-peluqueria\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mobiliario de peluquer\u00eda\",\"item\":\"https:\\\/\\\/salonforall.es\\\/equipamiento-de-peluqueria\\\/mobiliario-de-peluqueria\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Sillones y lavabos de peluquer\u00eda\",\"item\":\"https:\\\/\\\/salonforall.es\\\/equipamiento-de-peluqueria\\\/mobiliario-de-peluqueria\\\/sillones-y-lavabos-de-peluqueria\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Prato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/#website\",\"url\":\"https:\\\/\\\/salonforall.es\\\/\",\"name\":\"Salon For ALL Espa\u00f1a\",\"description\":\"Mayorista de mobiliario y suministros para consultorios y salones\",\"publisher\":{\"@id\":\"https:\\\/\\\/salonforall.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/salonforall.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/#organization\",\"name\":\"Salon For All B.V. Espa\u00f1a\",\"alternateName\":\"Salon For All B.V. Espa\u00f1a - Mayorista de equipamiento para consultas, salones y suministros\",\"url\":\"https:\\\/\\\/salonforall.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/salonforall.es\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-salon-for-all-e1764543185849.png\",\"contentUrl\":\"https:\\\/\\\/salonforall.es\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-salon-for-all-e1764543185849.png\",\"width\":500,\"height\":150,\"caption\":\"Salon For All B.V. Espa\u00f1a\"},\"image\":{\"@id\":\"https:\\\/\\\/salonforall.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prato - Sal\u00e3o de beleza para toda a Espanha","description":"Compre o seu Prato na Salon For ALL Espanha. O grossista em Espanha e Portugal para todos os sal\u00f5es. Mais de 10.000 produtos em linha.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/salonforall.es\/pt\/equipamento-de-cabeleireiro\/mobiliario-de-cabeleireiro\/cadeiras-de-cabeleireiro-e-lavatorios\/prato\/","og_locale":"pt_PT","og_type":"article","og_title":"Prato - Salon For ALL Espa\u00f1a","og_description":"Compra tu Prato en Salon For ALL Espa\u00f1a. El mayorista en Espa\u00f1a y Portugal para cada sal\u00f3n. M\u00e1s de 10.000 productos online.","og_url":"https:\/\/salonforall.es\/pt\/equipamento-de-cabeleireiro\/mobiliario-de-cabeleireiro\/cadeiras-de-cabeleireiro-e-lavatorios\/prato\/","og_site_name":"Salon For ALL Espa\u00f1a","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/salonforall.es\/equipamiento-de-peluqueria\/mobiliario-de-peluqueria\/sillones-y-lavabos-de-peluqueria\/prato\/","url":"https:\/\/salonforall.es\/equipamiento-de-peluqueria\/mobiliario-de-peluqueria\/sillones-y-lavabos-de-peluqueria\/prato\/","name":"Prato - Sal\u00e3o de beleza para toda a Espanha","isPartOf":{"@id":"https:\/\/salonforall.es\/#website"},"description":"Compre o seu Prato na Salon For ALL Espanha. O grossista em Espanha e Portugal para todos os sal\u00f5es. Mais de 10.000 produtos em linha.","breadcrumb":{"@id":"https:\/\/salonforall.es\/equipamiento-de-peluqueria\/mobiliario-de-peluqueria\/sillones-y-lavabos-de-peluqueria\/prato\/#breadcrumb"},"inLanguage":"pt-PT"},{"@type":"BreadcrumbList","@id":"https:\/\/salonforall.es\/equipamiento-de-peluqueria\/mobiliario-de-peluqueria\/sillones-y-lavabos-de-peluqueria\/prato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/salonforall.es\/"},{"@type":"ListItem","position":2,"name":"Equipamiento de peluquer\u00eda","item":"https:\/\/salonforall.es\/equipamiento-de-peluqueria\/"},{"@type":"ListItem","position":3,"name":"Mobiliario de peluquer\u00eda","item":"https:\/\/salonforall.es\/equipamiento-de-peluqueria\/mobiliario-de-peluqueria\/"},{"@type":"ListItem","position":4,"name":"Sillones y lavabos de peluquer\u00eda","item":"https:\/\/salonforall.es\/equipamiento-de-peluqueria\/mobiliario-de-peluqueria\/sillones-y-lavabos-de-peluqueria\/"},{"@type":"ListItem","position":5,"name":"Prato"}]},{"@type":"WebSite","@id":"https:\/\/salonforall.es\/#website","url":"https:\/\/salonforall.es\/","name":"Sal\u00e3o de beleza para toda a Espanha","description":"Grossista de mobili\u00e1rio e material para sal\u00f5es de beleza e consult\u00f3rios","publisher":{"@id":"https:\/\/salonforall.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/salonforall.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/salonforall.es\/#organization","name":"Salon For All B.V. Espanha","alternateName":"Salon For All B.V. Espa\u00f1a - Mayorista de equipamiento para consultas, salones y suministros","url":"https:\/\/salonforall.es\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/salonforall.es\/#\/schema\/logo\/image\/","url":"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/11\/logo-salon-for-all-e1764543185849.png","contentUrl":"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/11\/logo-salon-for-all-e1764543185849.png","width":500,"height":150,"caption":"Salon For All B.V. Espa\u00f1a"},"image":{"@id":"https:\/\/salonforall.es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/salonforall.es\/pt\/wp-json\/wp\/v2\/product_cat\/3484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salonforall.es\/pt\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/salonforall.es\/pt\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/salonforall.es\/pt\/wp-json\/wp\/v2\/product_cat\/98"}],"wp:post_type":[{"href":"https:\/\/salonforall.es\/pt\/wp-json\/wp\/v2\/product?product_cat=3484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}