{"id":2589,"count":1,"description":"","link":"https:\/\/salonforall.es\/pt\/cosmetica-profesional\/cosmetica-farmona\/acidos\/","name":"\u00c1cidos","slug":"acidos","taxonomy":"product_cat","parent":2562,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c1cidos - Salon For ALL Espa\u00f1a<\/title>\n<meta name=\"description\" content=\"Compra tu \u00c1cidos en Salon For ALL Espa\u00f1a. El mayorista en Espa\u00f1a y Portugal para cada sal\u00f3n. M\u00e1s de 10.000 productos online.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/salonforall.es\/pt\/cosmeticos-profissionais\/cosmeticos-farmona\/acidos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c1cidos - Salon For ALL Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"Compra tu \u00c1cidos en Salon For ALL Espa\u00f1a. El mayorista en Espa\u00f1a y Portugal para cada sal\u00f3n. M\u00e1s de 10.000 productos online.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/salonforall.es\/pt\/cosmeticos-profissionais\/cosmeticos-farmona\/acidos\/\" \/>\n<meta property=\"og:site_name\" content=\"Salon For ALL Espa\u00f1a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/cosmetica-profesional\\\/cosmetica-farmona\\\/acidos\\\/\",\"url\":\"https:\\\/\\\/salonforall.es\\\/cosmetica-profesional\\\/cosmetica-farmona\\\/acidos\\\/\",\"name\":\"\u00c1cidos - Salon For ALL Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/salonforall.es\\\/#website\"},\"description\":\"Compra tu \u00c1cidos en Salon For ALL Espa\u00f1a. El mayorista en Espa\u00f1a y Portugal para cada sal\u00f3n. M\u00e1s de 10.000 productos online.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/salonforall.es\\\/cosmetica-profesional\\\/cosmetica-farmona\\\/acidos\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/cosmetica-profesional\\\/cosmetica-farmona\\\/acidos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/salonforall.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cosm\u00e9tica profesional\",\"item\":\"https:\\\/\\\/salonforall.es\\\/cosmetica-profesional\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cosm\u00e9tica FARMONA\",\"item\":\"https:\\\/\\\/salonforall.es\\\/cosmetica-profesional\\\/cosmetica-farmona\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u00c1cidos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/#website\",\"url\":\"https:\\\/\\\/salonforall.es\\\/\",\"name\":\"Salon For ALL Espa\u00f1a\",\"description\":\"Mayorista de mobiliario y suministros para consultorios y salones\",\"publisher\":{\"@id\":\"https:\\\/\\\/salonforall.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/salonforall.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/#organization\",\"name\":\"Salon For All B.V. Espa\u00f1a\",\"alternateName\":\"Salon For All B.V. Espa\u00f1a - Mayorista de equipamiento para consultas, salones y suministros\",\"url\":\"https:\\\/\\\/salonforall.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/salonforall.es\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-salon-for-all-e1764543185849.png\",\"contentUrl\":\"https:\\\/\\\/salonforall.es\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-salon-for-all-e1764543185849.png\",\"width\":500,\"height\":150,\"caption\":\"Salon For All B.V. Espa\u00f1a\"},\"image\":{\"@id\":\"https:\\\/\\\/salonforall.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c1cidos - Salon For ALL Espa\u00f1a","description":"Compra tu \u00c1cidos en Salon For ALL Espa\u00f1a. El mayorista en Espa\u00f1a y Portugal para cada sal\u00f3n. M\u00e1s de 10.000 productos online.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/salonforall.es\/pt\/cosmeticos-profissionais\/cosmeticos-farmona\/acidos\/","og_locale":"pt_PT","og_type":"article","og_title":"\u00c1cidos - Salon For ALL Espa\u00f1a","og_description":"Compra tu \u00c1cidos en Salon For ALL Espa\u00f1a. El mayorista en Espa\u00f1a y Portugal para cada sal\u00f3n. M\u00e1s de 10.000 productos online.","og_url":"https:\/\/salonforall.es\/pt\/cosmeticos-profissionais\/cosmeticos-farmona\/acidos\/","og_site_name":"Salon For ALL Espa\u00f1a","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/salonforall.es\/cosmetica-profesional\/cosmetica-farmona\/acidos\/","url":"https:\/\/salonforall.es\/cosmetica-profesional\/cosmetica-farmona\/acidos\/","name":"\u00c1cidos - Salon For ALL Espa\u00f1a","isPartOf":{"@id":"https:\/\/salonforall.es\/#website"},"description":"Compra tu \u00c1cidos en Salon For ALL Espa\u00f1a. El mayorista en Espa\u00f1a y Portugal para cada sal\u00f3n. M\u00e1s de 10.000 productos online.","breadcrumb":{"@id":"https:\/\/salonforall.es\/cosmetica-profesional\/cosmetica-farmona\/acidos\/#breadcrumb"},"inLanguage":"pt-PT"},{"@type":"BreadcrumbList","@id":"https:\/\/salonforall.es\/cosmetica-profesional\/cosmetica-farmona\/acidos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/salonforall.es\/"},{"@type":"ListItem","position":2,"name":"Cosm\u00e9tica profesional","item":"https:\/\/salonforall.es\/cosmetica-profesional\/"},{"@type":"ListItem","position":3,"name":"Cosm\u00e9tica FARMONA","item":"https:\/\/salonforall.es\/cosmetica-profesional\/cosmetica-farmona\/"},{"@type":"ListItem","position":4,"name":"\u00c1cidos"}]},{"@type":"WebSite","@id":"https:\/\/salonforall.es\/#website","url":"https:\/\/salonforall.es\/","name":"Sal\u00e3o de beleza para toda a Espanha","description":"Grossista de mobili\u00e1rio e material para sal\u00f5es de beleza e consult\u00f3rios","publisher":{"@id":"https:\/\/salonforall.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/salonforall.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/salonforall.es\/#organization","name":"Salon For All B.V. Espanha","alternateName":"Salon For All B.V. Espa\u00f1a - Mayorista de equipamiento para consultas, salones y suministros","url":"https:\/\/salonforall.es\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/salonforall.es\/#\/schema\/logo\/image\/","url":"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/11\/logo-salon-for-all-e1764543185849.png","contentUrl":"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/11\/logo-salon-for-all-e1764543185849.png","width":500,"height":150,"caption":"Salon For All B.V. Espa\u00f1a"},"image":{"@id":"https:\/\/salonforall.es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/salonforall.es\/pt\/wp-json\/wp\/v2\/product_cat\/2589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salonforall.es\/pt\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/salonforall.es\/pt\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/salonforall.es\/pt\/wp-json\/wp\/v2\/product_cat\/2562"}],"wp:post_type":[{"href":"https:\/\/salonforall.es\/pt\/wp-json\/wp\/v2\/product?product_cat=2589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}