{"id":6615,"date":"2025-12-02T12:30:29","date_gmt":"2025-12-02T11:30:29","guid":{"rendered":"https:\/\/salonforall.es\/product\/gabbiano-infrazon-de-pie-868-1-negro\/"},"modified":"2026-03-24T16:40:54","modified_gmt":"2026-03-24T15:40:54","slug":"gabbiano-infrazon-de-pie-868-1-negro","status":"publish","type":"product","link":"https:\/\/salonforall.es\/pt\/gabbiano-infrazon-de-pie-868-1-negro\/","title":{"rendered":"Bra\u00e7o do suporte de ch\u00e3o Gabbiano 868-1 Preto"},"content":{"rendered":"<h2>Informaci\u00f3n sobre Gabbiano Infraz\u00f3n De Pie 868-1 Negro con n\u00famero de art\u00edculo 128919<\/h2>\n<div>\n<div>\n<div> infrazon es un dispositivo utilizado para acelerar los tratamientos qu\u00edmicos y de cuidado del cabello. hair infra-red es un dispositivo que acorta el tiempo de ondulaci\u00f3n permanente, aclaraci\u00f3n, te\u00f1ido o simplemente aplicar una m\u00e1scara y absorberla m\u00e1s r\u00e1pido y mejor en el cabello. infrazon acorta significativamente el tiempo de tratamiento, ahorrando as\u00ed el tiempo del peluquero y del cliente. El ajuste electr\u00f3nico de par\u00e1metros facilita significativamente el trabajo del peluquero. <\/div>\n<div> dispositivos disponibles en una versi\u00f3n colgante y en un tr\u00edpode. <\/div>\n<div> <\/div>\n<div>\n<div> implementa\u00e7\u00e3o: <br \/> &#8211; permanente, <br \/> &#8211; te\u00f1ido, <br \/> &#8211; abrillantador, <br \/> &#8211; termoestimulaci\u00f3n de tratamientos de peluquer\u00eda. <\/div>\n<div> <\/div>\n<div>\n<div> dados t\u00e9cnicos: <\/div>\n<div> 1600 vatios de potencia <\/div>\n<div>\n<div> control de temperatura 70-90 \u00b0C <\/div><\/div>\n<div> 5 cabezales de calentamiento <\/div>\n<div> 5 ventiladores <\/div><\/div>\n<div> <\/div>\n<\/div>\n<\/div><\/div>\n<p>Los productos Activeshop son proporcionalmente m\u00e1s econ\u00f3micos que muchas otras marcas\/proveedores. El precio est\u00e1 en relaci\u00f3n con la calidad. Gabbiano Infraz\u00f3n De Pie 868-1 Negro es por lo tanto una soluci\u00f3n accesible para su sal\u00f3n.<\/p>\n<h2>\u00bfC\u00f3mo se entrega Gabbiano Infraz\u00f3n De Pie 868-1 Negro?<\/h2>\n<p>Gabbiano Infraz\u00f3n De Pie 868-1 Negro se entrega en embalaje(s) original(es). Dentro de Espa\u00f1a el env\u00edo de Gabbiano Infraz\u00f3n De Pie 868-1 Negro es completamente gratuito para pedidos a partir de 100,- euros. Para env\u00edos a otros pa\u00edses se aplican tarifas de env\u00edo separadas. Puede consultar estas tarifas con nosotros o verlas en el carrito de compra. Gabbiano Infraz\u00f3n De Pie 868-1 Negro se env\u00eda a trav\u00e9s de un servicio de mensajer\u00eda externo.<\/p>\n<p>As encomendas ou paletes s\u00e3o entregues, por norma, at\u00e9 \u00e0 soleira da porta da frente, mesmo que se encontre num edif\u00edcio coletivo, num edif\u00edcio de apartamentos ou num complexo de apartamentos com elevador (desde que o artigo caiba no elevador). N\u00e3o h\u00e1 elevador dispon\u00edvel ou o artigo n\u00e3o cabe no elevador? Ent\u00e3o entregamos at\u00e9 \u00e0 soleira do r\u00e9s do ch\u00e3o.<\/p>\n<p>Se ainda tem d\u00favidas sobre a entrega ou uma situa\u00e7\u00e3o especial, contacte-nos e teremos todo o gosto em ajud\u00e1-lo!<\/p>\n<p>*Os artigos n\u00e3o s\u00e3o desempacotados ou montados como padr\u00e3o. Em situa\u00e7\u00f5es especiais, pode contactar-nos para combinarmos as condi\u00e7\u00f5es.<\/p>\n<h2>Compras online seguras na Salon For All com o selo de qualidade Webwinkelkeur e encripta\u00e7\u00e3o SSL.<\/h2>\n<p>Es importante para nosotros que nuestros clientes puedan comprar de forma segura en nuestra tienda online. Estamos afiliados al sello de calidad nacional Webwinkelkeur desde 2019. Nuestra identidad ha sido verificada y comprobada por ellos, y la tienda online ha sido revisada y aprobada legalmente. Adem\u00e1s, nuestra tienda online est\u00e1 afiliada a ellos para la mediaci\u00f3n de conflictos. Puede ver la insignia con toda la informaci\u00f3n de este sello de calidad de tienda online en el lado izquierdo o derecho de la tienda online (bot\u00f3n rosa con blanco). Adem\u00e1s, nuestro sitio est\u00e1 protegido con un certificado SSL para que pueda navegar de forma segura con nosotros. En la barra de su navegador de Internet, donde aparece nuestro sitio web, ver\u00e1 un icono de candado. Si hace clic en el candado, obtendr\u00e1 toda la informaci\u00f3n sobre nuestra seguridad. De esta manera sabe que su pedido de Gabbiano Infraz\u00f3n De Pie 868-1 Negro y sus datos personales se procesan de forma segura.<\/p>\n<h2>\u00bfC\u00f3mo puedo pagar Gabbiano Infraz\u00f3n De Pie 868-1 Negro?<\/h2>\n<p>Queremos tornar as coisas o mais f\u00e1ceis poss\u00edvel para si. \u00c9 por isso que na Salon For All pode pagar com todos os m\u00e9todos de pagamento populares. Pagar antecipadamente, na entrega ou depois - tudo \u00e9 poss\u00edvel. Veja aqui todos os m\u00e9todos de pagamento que oferecemos:<\/p>\n<ul>\n<li>iDEAL<\/li>\n<li>Cart\u00e3o de cr\u00e9dito (Visa, Mastercard, American Express)<\/li>\n<li>Klarna - Pagamento na entrega com fatura<\/li>\n<li>PayPal<\/li>\n<li>Apple Pay<\/li>\n<li>Google Pay<\/li>\n<li>Bizum (para clientes espanh\u00f3is)<\/li>\n<li>Transfer\u00eancia banc\u00e1ria SEPA<\/li>\n<li>Contacto com o banco<\/li>\n<li>Fatura comercial para empresas<\/li>\n<li>Pagamento na sala de exposi\u00e7\u00f5es - Cart\u00e3o e dinheiro (apenas dispon\u00edvel \u00e0 cobran\u00e7a)<\/li>\n<\/ul>\n<h2>Veja tamb\u00e9m as opini\u00f5es de Salon For All<\/h2>\n<p>Consulte tambi\u00e9n nuestras rese\u00f1as para tener en cuenta las experiencias de nuestros clientes actuales en su decisi\u00f3n de pedir Gabbiano Infraz\u00f3n De Pie 868-1 Negro con nosotros. A trav\u00e9s de nuestro sello de calidad independiente de tienda online Webwinkelkeur, se recopilan autom\u00e1ticamente rese\u00f1as verificadas de clientes que han completado un pedido con nosotros. Puede encontrarlas detr\u00e1s del bot\u00f3n rosa en nuestra tienda online o aparecen listadas debajo de los productos.<\/p>\n<p>\u00a1Comparta tambi\u00e9n su experiencia despu\u00e9s de su compra con su Gabbiano Infraz\u00f3n De Pie 868-1 Negro pedido y su experiencia con el proceso de compra o el contacto con Salon For All para inspirar a otros!<\/p>\n<h2>Contactar o Salon For All<\/h2>\n<p>Cont\u00e1ctenos entonces. Estaremos encantados de ayudarle con la adquisici\u00f3n de Gabbiano Infraz\u00f3n De Pie 868-1 Negro. En d\u00edas laborables estamos mejor disponibles entre las 8.30 y las 17.00 horas a trav\u00e9s del n\u00famero de tel\u00e9fono y direcci\u00f3n de correo electr\u00f3nico en la parte superior de la tienda online o a trav\u00e9s de la funci\u00f3n de chat. Las consultas fuera del horario de oficina suelen responderse en un plazo de 24 horas. Tambi\u00e9n es posible visitarnos fuera de los d\u00edas laborables u horario de oficina. Pero para ello es necesario concertar una cita previa.<\/p>\n<h2>Gostaria de visitar a nossa sala de exposi\u00e7\u00f5es?<\/h2>\n<p>\u00bfPrefiere ver Gabbiano Infraz\u00f3n De Pie 868-1 Negro o recorrer nuestra oferta de la tienda (online) junto con nuestro colega? Entonces visite nuestro showroom con m\u00e1s de 1000m\u00b2 de equipamiento para salones y d\u00e9jese inspirar por nuestros empleados. Tambi\u00e9n si le gusta conocernos de manera agradable disfrutando de una buena taza de caf\u00e9 o t\u00e9, es muy bienvenido. No tenemos todos los productos en stock, as\u00ed que h\u00e1ganos saber de antemano que desea venir. Concierte siempre una cita previa.<\/p>\n<h2>14 dias de reflex\u00e3o e a nossa pol\u00edtica de devolu\u00e7\u00e3o<\/h2>\n<p>Por supuesto puede ocurrir que Gabbiano Infraz\u00f3n De Pie 868-1 Negro entregado no sea completamente de su agrado y desee devolverlo. Eso no es ning\u00fan problema en Salon For All. Debe notificar su devoluci\u00f3n dentro de 14 d\u00edas laborables a trav\u00e9s de info@salonforall.es. Entonces recibir\u00e1 primero todas las instrucciones y condiciones de devoluci\u00f3n. Tenga en cuenta que Gabbiano Infraz\u00f3n De Pie 868-1 Negro no debe haber sido usado, debe contener todas las partes suministradas y debe devolverse empaquetado en el embalaje original. Los costos de env\u00edo de una devoluci\u00f3n son siempre a cargo del comprador en compras a trav\u00e9s de www.salonforall.es. Debe organizar usted mismo un transporte con una empresa de transporte de su elecci\u00f3n para una devoluci\u00f3n. Una vez que Gabbiano Infraz\u00f3n De Pie 868-1 Negro haya sido devuelto, se verificar\u00e1 su integridad y posibles da\u00f1os. Una vez que la devoluci\u00f3n haya sido aprobada, el importe de la compra se reembolsar\u00e1 dentro de 5 d\u00edas laborables a la cuenta bancaria que tenemos registrada.<\/p>\n<h2>Quem \u00e9 o Salon For All?<\/h2>\n<p>A Salon For All \u00e9 o grossista de todo o equipamento para sal\u00f5es de beleza na Europa. A Salon For All come\u00e7ou em 2003 com o nome Salonvoordeel e cresceu a partir da pr\u00e1tica. Os propriet\u00e1rios da Salon For All eram cabeleireiros experientes e especialistas em beleza e t\u00eam, em conjunto, mais de 30 anos de experi\u00eancia pr\u00e1tica. Em 2003, lan\u00e7\u00e1mos o Salonvoordeel.nl (Pa\u00edses Baixos) e, posteriormente, o Salon For All foi fundado para o mercado europeu. Alguns dos nossos funcion\u00e1rios come\u00e7aram o seu pr\u00f3prio neg\u00f3cio e assim nasceu a ideia de lan\u00e7ar uma loja online funcional para cabeleireiros e para os ajudar com o seu equipamento de sal\u00e3o.<\/p>\n<p>Nuestro showroom se encuentra en Dinxperlo, directamente en la frontera entre los Pa\u00edses Bajos y Alemania. Con nuestra amplia experiencia en el sector podemos servirle de espejo y proporcionarle el asesoramiento adecuado. \u00a1Hablamos el mismo idioma! Le asesoramos, inspiramos, motivamos y ayudamos en la adquisici\u00f3n de Gabbiano Infraz\u00f3n De Pie 868-1 Negro. Nuestros proveedores se encuentran en toda Europa, desde Alemania, Inglaterra, Italia hasta Polonia.<\/p>","protected":false},"excerpt":{"rendered":"<p>O suporte de ch\u00e3o Gabbiano Infrazon 868-1 Preto \u00e9 uma solu\u00e7\u00e3o de alta qualidade para qualquer sala de estar. O prazo de entrega estimado \u00e9 de aproximadamente 6 dias \u00fateis.<\/p>","protected":false},"featured_media":6616,"comment_status":"open","ping_status":"open","template":"","meta":[],"product_brand":[95],"product_cat":[114,96,115],"product_tag":[100,116],"class_list":{"0":"post-6615","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-gabbiano","7":"product_cat-equipamiento-de-peluqueria-equipamiento-de-peluqueria","8":"product_cat-equipamiento-de-peluqueria","9":"product_cat-saunas-e-infrasonadores-gabbiano","10":"product_tag-equipamiento-de-peluqueria","11":"product_tag-saunas-e-infrasonadores-gabbiano","12":"pa_codigo-ean-7759","13":"pa_garantia-12-meses","14":"pa_marca-gabbiano","15":"pa_numero-de-articulo-2282","16":"pa_tiempo-estimado-de-entrega-4-5-dias-laborables","18":"first","19":"instock","20":"sale","21":"taxable","22":"shipping-taxable","23":"purchasable","24":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gabbiano Infraz\u00f3n De Pie 868-1 Negro comprar<\/title>\n<meta name=\"description\" content=\"Compra Gabbiano Infraz\u00f3n De Pie 868-1 Negro online o en el showroom en Salon For ALL Espa\u00f1a. El mayorista para salones, consultas y spas en Espa\u00f1a y Portugal.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/salonforall.es\/pt\/gabbiano-infrazon-de-pie-868-1-negro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gabbiano Infraz\u00f3n De Pie 868-1 Negro\" \/>\n<meta property=\"og:description\" content=\"Compra Gabbiano Infraz\u00f3n De Pie 868-1 Negro online o en el showroom en Salon For ALL Espa\u00f1a. El mayorista para salones, consultas y spas en Espa\u00f1a y Portugal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/salonforall.es\/pt\/gabbiano-infrazon-de-pie-868-1-negro\/\" \/>\n<meta property=\"og:site_name\" content=\"Salon For ALL Espa\u00f1a\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-24T15:40:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/Gabbiano-Infrazon-De-Pie-868-1-Negro.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Gabbiano Infraz\u00f3n De Pie 868-1 Negro\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/gabbiano-infrazon-de-pie-868-1-negro\\\/\",\"url\":\"https:\\\/\\\/salonforall.es\\\/gabbiano-infrazon-de-pie-868-1-negro\\\/\",\"name\":\"Gabbiano Infraz\u00f3n De Pie 868-1 Negro comprar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/salonforall.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/salonforall.es\\\/gabbiano-infrazon-de-pie-868-1-negro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/salonforall.es\\\/gabbiano-infrazon-de-pie-868-1-negro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/salonforall.es\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Gabbiano-Infrazon-De-Pie-868-1-Negro.jpg\",\"datePublished\":\"2025-12-02T11:30:29+00:00\",\"dateModified\":\"2026-03-24T15:40:54+00:00\",\"description\":\"Compra Gabbiano Infraz\u00f3n De Pie 868-1 Negro online o en el showroom en Salon For ALL Espa\u00f1a. El mayorista para salones, consultas y spas en Espa\u00f1a y Portugal.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/salonforall.es\\\/gabbiano-infrazon-de-pie-868-1-negro\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/salonforall.es\\\/gabbiano-infrazon-de-pie-868-1-negro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/gabbiano-infrazon-de-pie-868-1-negro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/salonforall.es\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Gabbiano-Infrazon-De-Pie-868-1-Negro.jpg\",\"contentUrl\":\"https:\\\/\\\/salonforall.es\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Gabbiano-Infrazon-De-Pie-868-1-Negro.jpg\",\"width\":800,\"height\":800,\"caption\":\"Gabbiano Infraz\u00f3n De Pie 868-1 Negro\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/gabbiano-infrazon-de-pie-868-1-negro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/salonforall.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Winkel\",\"item\":\"https:\\\/\\\/salonforall.es\\\/winkel\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gabbiano Infraz\u00f3n De Pie 868-1 Negro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/#website\",\"url\":\"https:\\\/\\\/salonforall.es\\\/\",\"name\":\"Salon For ALL Espa\u00f1a\",\"description\":\"Mayorista de mobiliario y suministros para consultorios y salones\",\"publisher\":{\"@id\":\"https:\\\/\\\/salonforall.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/salonforall.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/#organization\",\"name\":\"Salon For All B.V. Espa\u00f1a\",\"alternateName\":\"Salon For All B.V. Espa\u00f1a - Mayorista de equipamiento para consultas, salones y suministros\",\"url\":\"https:\\\/\\\/salonforall.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/salonforall.es\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-salon-for-all-e1764543185849.png\",\"contentUrl\":\"https:\\\/\\\/salonforall.es\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-salon-for-all-e1764543185849.png\",\"width\":500,\"height\":150,\"caption\":\"Salon For All B.V. Espa\u00f1a\"},\"image\":{\"@id\":\"https:\\\/\\\/salonforall.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gabbiano Infraz\u00f3n De Pie 868-1 Negro comprar","description":"Compra Gabbiano Infraz\u00f3n De Pie 868-1 Negro online o en el showroom en Salon For ALL Espa\u00f1a. El mayorista para salones, consultas y spas en Espa\u00f1a y Portugal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/salonforall.es\/pt\/gabbiano-infrazon-de-pie-868-1-negro\/","og_locale":"pt_PT","og_type":"article","og_title":"Gabbiano Infraz\u00f3n De Pie 868-1 Negro","og_description":"Compra Gabbiano Infraz\u00f3n De Pie 868-1 Negro online o en el showroom en Salon For ALL Espa\u00f1a. El mayorista para salones, consultas y spas en Espa\u00f1a y Portugal.","og_url":"https:\/\/salonforall.es\/pt\/gabbiano-infrazon-de-pie-868-1-negro\/","og_site_name":"Salon For ALL Espa\u00f1a","article_modified_time":"2026-03-24T15:40:54+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/Gabbiano-Infrazon-De-Pie-868-1-Negro.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Gabbiano Infraz\u00f3n De Pie 868-1 Negro","twitter_misc":{"Tempo estimado de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/salonforall.es\/gabbiano-infrazon-de-pie-868-1-negro\/","url":"https:\/\/salonforall.es\/gabbiano-infrazon-de-pie-868-1-negro\/","name":"Gabbiano Infraz\u00f3n De Pie 868-1 Negro comprar","isPartOf":{"@id":"https:\/\/salonforall.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/salonforall.es\/gabbiano-infrazon-de-pie-868-1-negro\/#primaryimage"},"image":{"@id":"https:\/\/salonforall.es\/gabbiano-infrazon-de-pie-868-1-negro\/#primaryimage"},"thumbnailUrl":"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/Gabbiano-Infrazon-De-Pie-868-1-Negro.jpg","datePublished":"2025-12-02T11:30:29+00:00","dateModified":"2026-03-24T15:40:54+00:00","description":"Compra Gabbiano Infraz\u00f3n De Pie 868-1 Negro online o en el showroom en Salon For ALL Espa\u00f1a. El mayorista para salones, consultas y spas en Espa\u00f1a y Portugal.","breadcrumb":{"@id":"https:\/\/salonforall.es\/gabbiano-infrazon-de-pie-868-1-negro\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/salonforall.es\/gabbiano-infrazon-de-pie-868-1-negro\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/salonforall.es\/gabbiano-infrazon-de-pie-868-1-negro\/#primaryimage","url":"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/Gabbiano-Infrazon-De-Pie-868-1-Negro.jpg","contentUrl":"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/Gabbiano-Infrazon-De-Pie-868-1-Negro.jpg","width":800,"height":800,"caption":"Gabbiano Infraz\u00f3n De Pie 868-1 Negro"},{"@type":"BreadcrumbList","@id":"https:\/\/salonforall.es\/gabbiano-infrazon-de-pie-868-1-negro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/salonforall.es\/"},{"@type":"ListItem","position":2,"name":"Winkel","item":"https:\/\/salonforall.es\/winkel\/"},{"@type":"ListItem","position":3,"name":"Gabbiano Infraz\u00f3n De Pie 868-1 Negro"}]},{"@type":"WebSite","@id":"https:\/\/salonforall.es\/#website","url":"https:\/\/salonforall.es\/","name":"Sal\u00e3o de beleza para toda a Espanha","description":"Grossista de mobili\u00e1rio e material para sal\u00f5es de beleza e consult\u00f3rios","publisher":{"@id":"https:\/\/salonforall.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/salonforall.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/salonforall.es\/#organization","name":"Salon For All B.V. Espanha","alternateName":"Salon For All B.V. Espa\u00f1a - Mayorista de equipamiento para consultas, salones y suministros","url":"https:\/\/salonforall.es\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/salonforall.es\/#\/schema\/logo\/image\/","url":"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/11\/logo-salon-for-all-e1764543185849.png","contentUrl":"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/11\/logo-salon-for-all-e1764543185849.png","width":500,"height":150,"caption":"Salon For All B.V. Espa\u00f1a"},"image":{"@id":"https:\/\/salonforall.es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/salonforall.es\/pt\/wp-json\/wp\/v2\/product\/6615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salonforall.es\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/salonforall.es\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/salonforall.es\/pt\/wp-json\/wp\/v2\/comments?post=6615"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/salonforall.es\/pt\/wp-json\/wp\/v2\/media\/6616"}],"wp:attachment":[{"href":"https:\/\/salonforall.es\/pt\/wp-json\/wp\/v2\/media?parent=6615"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/salonforall.es\/pt\/wp-json\/wp\/v2\/product_brand?post=6615"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/salonforall.es\/pt\/wp-json\/wp\/v2\/product_cat?post=6615"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/salonforall.es\/pt\/wp-json\/wp\/v2\/product_tag?post=6615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}