{"id":11246,"date":"2025-12-02T13:30:48","date_gmt":"2025-12-02T12:30:48","guid":{"rendered":"https:\/\/salonforall.es\/product\/calentador-de-cera-iwax-diamond-negro\/"},"modified":"2026-03-24T17:04:36","modified_gmt":"2026-03-24T16:04:36","slug":"aquecedor-de-cera-iwax-diamante-preto","status":"publish","type":"product","link":"https:\/\/salonforall.es\/pt\/calentador-de-cera-iwax-diamond-negro\/","title":{"rendered":"Aquecedor de cera Iwax Diamond Preto"},"content":{"rendered":"<h2>Informa\u00e7\u00f5es sobre o aquecedor de cera Iwax Diamond Wax Heater Black com o n\u00famero de item 144118<\/h2>\n<p><img decoding=\"async\" src=\"https:\/\/activeshop.com.pl\/media\/wysiwyg\/product\/144118\/EN_144118_1_1.jpg\"><\/p>\n<h2><strong>Aquecedor de cera com design exclusivo<\/strong><\/h2>\n<p>Aquecedor de cera profissional para depila\u00e7\u00e3o com um design \u00fanico. O aquecedor \u00e9 seguro e f\u00e1cil de utilizar. Inclui um recipiente de alum\u00ednio f\u00e1cil de remover.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/activeshop.com.pl\/media\/wysiwyg\/product\/144118\/EN_144118_1.jpg\"><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>As suas carater\u00edsticas s\u00e3o:<\/strong><\/h2>\n<p>- Tampa transparente para controlar a fus\u00e3o da cera e evitar o sobreaquecimento e a acumula\u00e7\u00e3o de p\u00f3.<br \/>- Temperatura na gama de 35\u00b0 a 120\u00b0 Celsius regul\u00e1vel por meio de um bot\u00e3o.<br \/>- L\u00e2mpada de controlo e sistema de cliques (cliques quando o bot\u00e3o \u00e9 movido para indicar que o dispositivo est\u00e1 ligado\/desligado).<\/p>\n<p>Adequado para cera normal, missangas, blocos e cera de parafina.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/activeshop.com.pl\/media\/wysiwyg\/product\/144118\/EN_144118_2.jpg\"><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Como o utilizar?<\/strong><\/h2>\n<p>1. ligar o aparelho \u00e0 alimenta\u00e7\u00e3o el\u00e9ctrica. Colocar os gr\u00e2nulos de cera ou a cera enlatada numa panela e, em seguida, coloc\u00e1-la no aquecedor.<br \/>2) Rode o bot\u00e3o para a posi\u00e7\u00e3o ON; a luz vermelha indica que o aparelho come\u00e7ou a funcionar.<br \/>3) Durante o funcionamento do aparelho, a luz deve ser desligada e ligada de novo para manter uma temperatura constante da cera.<br \/>4. A cera demora 10 a 30 minutos a dissolver-se, consoante a temperatura selecionada.<br \/>5. Verificar sempre a temperatura da cera antes de a aplicar na pele para evitar queimaduras.<br \/>6. Ap\u00f3s a utiliza\u00e7\u00e3o, desligue o aparelho e aguarde que arrefe\u00e7a.<br \/>7. O aparelho pode ser limpo quando est\u00e1 desligado da rede el\u00e9ctrica.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Dados t\u00e9cnicos:<\/strong><\/h2>\n<p>Modelo: AX800<br \/>Tens\u00e3o: 220 V \/ 240 V<br \/>Pot\u00eancia el\u00e9ctrica: 100 W<br \/>Frequ\u00eancia: 50 \/ 60 Hz<\/p>\n<div class=\"video-container\"><iframe height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/mfzMv5oOkoI\" frameborder=\"0\" width=\"560\" allowfullscreen allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\"> <\/iframe><\/div>\n<p>Os produtos da Activeshop s\u00e3o proporcionalmente mais baratos do que os de muitas outras marcas\/fornecedores. O pre\u00e7o est\u00e1 em rela\u00e7\u00e3o com a qualidade. O aquecedor de cera Iwax Diamond Black \u00e9, portanto, uma solu\u00e7\u00e3o econ\u00f3mica para o seu sal\u00e3o.<\/p>\n<h2>Como \u00e9 entregue o aquecedor de cera Iwax Diamond Black?<\/h2>\n<p>O Calentador De Cera Iwax Diamond Negro \u00e9 entregue na(s) embalagem(ns) original(ais). Em Espanha, o envio de Calentador De Cera Iwax Diamond Negro \u00e9 totalmente gratuito para encomendas superiores a 100,- Euro. Para envios para outros pa\u00edses, aplicam-se taxas de envio separadas. Pode verificar estas taxas connosco ou v\u00ea-las no carrinho de compras. O Calentador De Cera Iwax Diamond Black \u00e9 enviado atrav\u00e9s de um servi\u00e7o de correio externo.<\/p>\n<p>As encomendas ou paletes s\u00e3o entregues, por norma, at\u00e9 \u00e0 soleira da porta da frente, mesmo que se encontre num edif\u00edcio coletivo, num edif\u00edcio de apartamentos ou num complexo de apartamentos com elevador (desde que o artigo caiba no elevador). N\u00e3o h\u00e1 elevador dispon\u00edvel ou o artigo n\u00e3o cabe no elevador? Ent\u00e3o entregamos at\u00e9 \u00e0 soleira do r\u00e9s do ch\u00e3o.<\/p>\n<p>Se ainda tem d\u00favidas sobre a entrega ou uma situa\u00e7\u00e3o especial, contacte-nos e teremos todo o gosto em ajud\u00e1-lo!<\/p>\n<p>*Os artigos n\u00e3o s\u00e3o desempacotados ou montados como padr\u00e3o. Em situa\u00e7\u00f5es especiais, pode contactar-nos para combinarmos as condi\u00e7\u00f5es.<\/p>\n<h2>Compras online seguras na Salon For All com o selo de qualidade Webwinkelkeur e encripta\u00e7\u00e3o SSL.<\/h2>\n<p>\u00c9 importante para n\u00f3s que os nossos clientes possam fazer compras com seguran\u00e7a na nossa loja online. Estamos afiliados ao selo de qualidade nacional Webwinkelkeur desde 2019. A nossa identidade foi verificada e verificada por eles, e a loja online foi verificada e legalmente aprovada. Al\u00e9m disso, a nossa loja online \u00e9 afiliada a eles para media\u00e7\u00e3o de conflitos. Pode ver o log\u00f3tipo com todas as informa\u00e7\u00f5es deste selo de qualidade da loja online no lado esquerdo ou direito da loja online (bot\u00e3o rosa com branco). Al\u00e9m disso, o nosso s\u00edtio est\u00e1 protegido por um certificado SSL para que possa navegar em seguran\u00e7a connosco. Na barra do seu navegador de Internet, onde aparece o nosso s\u00edtio Web, ver\u00e1 um \u00edcone de cadeado. Se clicar no cadeado, obter\u00e1 todas as informa\u00e7\u00f5es sobre a nossa seguran\u00e7a. Desta forma, sabe que a sua encomenda Iwax Diamond Wax Warmer Black e os seus dados pessoais s\u00e3o tratados de forma segura.<\/p>\n<h2>Como posso pagar o aquecedor de cera Iwax Diamond Black?<\/h2>\n<p>Queremos tornar as coisas o mais f\u00e1ceis poss\u00edvel para si. \u00c9 por isso que na Salon For All pode pagar com todos os m\u00e9todos de pagamento populares. Pagar antecipadamente, na entrega ou depois - tudo \u00e9 poss\u00edvel. Veja aqui todos os m\u00e9todos de pagamento que oferecemos:<\/p>\n<ul>\n<li>iDEAL<\/li>\n<li>Cart\u00e3o de cr\u00e9dito (Visa, Mastercard, American Express)<\/li>\n<li>Klarna - Pagamento na entrega com fatura<\/li>\n<li>PayPal<\/li>\n<li>Apple Pay<\/li>\n<li>Google Pay<\/li>\n<li>Bizum (para clientes espanh\u00f3is)<\/li>\n<li>Transfer\u00eancia banc\u00e1ria SEPA<\/li>\n<li>Contacto com o banco<\/li>\n<li>Fatura comercial para empresas<\/li>\n<li>Pagamento na sala de exposi\u00e7\u00f5es - Cart\u00e3o e dinheiro (apenas dispon\u00edvel \u00e0 cobran\u00e7a)<\/li>\n<\/ul>\n<h2>Veja tamb\u00e9m as opini\u00f5es de Salon For All<\/h2>\n<p>Por favor, verifique tamb\u00e9m os nossos coment\u00e1rios para ter em conta as experi\u00eancias dos nossos clientes existentes na sua decis\u00e3o de encomendar Iwax Diamond Wax Heater Black connosco. Atrav\u00e9s do selo de qualidade da nossa loja online independente Webwinkelkeur, s\u00e3o recolhidas automaticamente as opini\u00f5es verificadas dos clientes que efectuaram uma encomenda connosco. Pode encontr\u00e1-las atr\u00e1s do bot\u00e3o cor-de-rosa na nossa loja online ou listadas por baixo dos produtos.<\/p>\n<p>Partilhe tamb\u00e9m a sua experi\u00eancia ap\u00f3s comprar o seu Aquecedor de cera preta Iwax Diamond e a sua experi\u00eancia com o processo de encomenda ou com o contacto da Salon For All para se inspirar nos outros!<\/p>\n<h2>Contactar o Salon For All<\/h2>\n<p>Contacte-nos ent\u00e3o. Teremos todo o gosto em ajud\u00e1-lo na compra do aquecedor de cera Iwax Diamond Black. Nos dias \u00fateis, estamos dispon\u00edveis entre as 8h30 e as 17h00, atrav\u00e9s do n\u00famero de telefone e do endere\u00e7o de correio eletr\u00f3nico indicados no topo da loja online ou atrav\u00e9s da fun\u00e7\u00e3o de chat. Os pedidos de informa\u00e7\u00e3o fora do hor\u00e1rio de expediente s\u00e3o normalmente respondidos no prazo de 24 horas. Tamb\u00e9m \u00e9 poss\u00edvel visitar-nos fora dos dias \u00fateis ou do hor\u00e1rio de expediente. No entanto, \u00e9 necess\u00e1rio efetuar uma marca\u00e7\u00e3o pr\u00e9via.<\/p>\n<h2>Gostaria de visitar a nossa sala de exposi\u00e7\u00f5es?<\/h2>\n<p>Prefere ver o aquecedor de cera Iwax Diamond Wax Heater Black ou deseja consultar a nossa oferta de loja (online) juntamente com o nosso colega? Ent\u00e3o visite o nosso showroom com mais de 1000m\u00b2 de equipamento para sal\u00f5es de beleza e deixe-se inspirar pelos nossos colaboradores. Al\u00e9m disso, se gosta de nos conhecer agradavelmente com uma ch\u00e1vena de caf\u00e9 ou ch\u00e1, \u00e9 muito bem-vindo. N\u00e3o temos todos os produtos em stock, por isso, por favor, avise-nos com anteced\u00eancia que gostaria de vir. Marque sempre uma visita com anteced\u00eancia.<\/p>\n<h2>14 dias de reflex\u00e3o e a nossa pol\u00edtica de devolu\u00e7\u00e3o<\/h2>\n<p>\u00c9 claro que pode acontecer que o aquecedor de cera Iwax Diamond Black entregue n\u00e3o seja totalmente do seu agrado e que o queira devolver. Isso n\u00e3o \u00e9 problema para a Salon For All. Deve notificar a sua devolu\u00e7\u00e3o no prazo de 14 dias \u00fateis atrav\u00e9s de info@salonforall.es. Receber\u00e1 ent\u00e3o, em primeiro lugar, todas as instru\u00e7\u00f5es e condi\u00e7\u00f5es de devolu\u00e7\u00e3o. O aquecedor de cera Iwax Diamond Wax Heater Black n\u00e3o deve ser utilizado, deve conter todas as pe\u00e7as fornecidas e deve ser devolvido na embalagem de origem. Os custos de transporte para uma devolu\u00e7\u00e3o s\u00e3o sempre a cargo do comprador nas compras efectuadas atrav\u00e9s do site www.salonforall.es. Deve ser o pr\u00f3prio comprador a organizar o transporte com uma transportadora \u00e0 sua escolha para uma devolu\u00e7\u00e3o. Uma vez devolvida a cera Iwax Wax Heater Diamond Black, ser\u00e1 verificada a sua integridade e eventuais danos. Uma vez aprovada a devolu\u00e7\u00e3o, o montante da compra ser\u00e1 reembolsado no prazo de 5 dias \u00fateis na conta banc\u00e1ria de que dispomos.<\/p>\n<h2>Quem \u00e9 o Salon For All?<\/h2>\n<p>A Salon For All \u00e9 o grossista de todo o equipamento para sal\u00f5es de beleza na Europa. A Salon For All come\u00e7ou em 2003 com o nome Salonvoordeel e cresceu a partir da pr\u00e1tica. Os propriet\u00e1rios da Salon For All eram cabeleireiros experientes e especialistas em beleza e t\u00eam, em conjunto, mais de 30 anos de experi\u00eancia pr\u00e1tica. Em 2003, lan\u00e7\u00e1mos o Salonvoordeel.nl (Pa\u00edses Baixos) e, posteriormente, o Salon For All foi fundado para o mercado europeu. Alguns dos nossos funcion\u00e1rios come\u00e7aram o seu pr\u00f3prio neg\u00f3cio e assim nasceu a ideia de lan\u00e7ar uma loja online funcional para cabeleireiros e para os ajudar com o seu equipamento de sal\u00e3o.<\/p>\n<p>O nosso showroom est\u00e1 situado em Dinxperlo, diretamente na fronteira entre os Pa\u00edses Baixos e a Alemanha. Com a nossa vasta experi\u00eancia no sector, podemos servir-lhe de espelho e dar-lhe os conselhos certos - falamos a mesma l\u00edngua! Aconselhamos, inspiramos, motivamos e apoiamo-lo na compra do aquecedor de cera preta Iwax Diamond. Os nossos fornecedores est\u00e3o localizados em toda a Europa, desde a Alemanha, Inglaterra, It\u00e1lia at\u00e9 \u00e0 Pol\u00f3nia.<\/p>","protected":false},"excerpt":{"rendered":"<p>O aquecedor de cera Iwax Diamond Black \u00e9 uma solu\u00e7\u00e3o de alta qualidade para qualquer sal\u00e3o de beleza. O prazo de entrega estimado \u00e9 de aproximadamente 6 dias \u00fateis.<\/p>","protected":false},"featured_media":11247,"comment_status":"open","ping_status":"open","template":"","meta":[],"product_brand":[512],"product_cat":[513,137],"product_tag":[514,140],"class_list":{"0":"post-11246","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-iwax","7":"product_cat-calentadores-de-cera","8":"product_cat-dispositivos-cosmeticos","9":"product_tag-calentadores-de-cera","10":"product_tag-dispositivos-cosmeticos","11":"pa_codigo-ean-7759","12":"pa_garantia-12-meses","13":"pa_marca-iwax","14":"pa_numero-de-articulo-4558","15":"pa_tiempo-estimado-de-entrega-4-5-dias-laborables","17":"first","18":"instock","19":"sale","20":"taxable","21":"shipping-taxable","22":"purchasable","23":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Calentador De Cera Iwax Diamond Negro comprar<\/title>\n<meta name=\"description\" content=\"Compra Calentador De Cera Iwax Diamond Negro online o en el showroom en Salon For ALL Espa\u00f1a. El mayorista para salones, consultas y spas en Espa\u00f1a y Portugal.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/salonforall.es\/pt\/aquecedor-de-cera-iwax-diamante-preto\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Calentador De Cera Iwax Diamond Negro\" \/>\n<meta property=\"og:description\" content=\"Compra Calentador De Cera Iwax Diamond Negro online o en el showroom en Salon For ALL Espa\u00f1a. El mayorista para salones, consultas y spas en Espa\u00f1a y Portugal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/salonforall.es\/pt\/aquecedor-de-cera-iwax-diamante-preto\/\" \/>\n<meta property=\"og:site_name\" content=\"Salon For ALL Espa\u00f1a\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-24T16:04:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/Calentador-De-Cera-Iwax-Diamond-Negro.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Calentador De Cera Iwax Diamond Negro\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/calentador-de-cera-iwax-diamond-negro\\\/\",\"url\":\"https:\\\/\\\/salonforall.es\\\/calentador-de-cera-iwax-diamond-negro\\\/\",\"name\":\"Calentador De Cera Iwax Diamond Negro comprar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/salonforall.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/salonforall.es\\\/calentador-de-cera-iwax-diamond-negro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/salonforall.es\\\/calentador-de-cera-iwax-diamond-negro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/salonforall.es\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Calentador-De-Cera-Iwax-Diamond-Negro.jpg\",\"datePublished\":\"2025-12-02T12:30:48+00:00\",\"dateModified\":\"2026-03-24T16:04:36+00:00\",\"description\":\"Compra Calentador De Cera Iwax Diamond Negro online o en el showroom en Salon For ALL Espa\u00f1a. El mayorista para salones, consultas y spas en Espa\u00f1a y Portugal.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/salonforall.es\\\/calentador-de-cera-iwax-diamond-negro\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/salonforall.es\\\/calentador-de-cera-iwax-diamond-negro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/calentador-de-cera-iwax-diamond-negro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/salonforall.es\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Calentador-De-Cera-Iwax-Diamond-Negro.jpg\",\"contentUrl\":\"https:\\\/\\\/salonforall.es\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Calentador-De-Cera-Iwax-Diamond-Negro.jpg\",\"width\":1200,\"height\":1200,\"caption\":\"Calentador De Cera Iwax Diamond Negro\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/calentador-de-cera-iwax-diamond-negro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/salonforall.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Winkel\",\"item\":\"https:\\\/\\\/salonforall.es\\\/winkel\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Calentador De Cera Iwax Diamond Negro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/#website\",\"url\":\"https:\\\/\\\/salonforall.es\\\/\",\"name\":\"Salon For ALL Espa\u00f1a\",\"description\":\"Mayorista de mobiliario y suministros para consultorios y salones\",\"publisher\":{\"@id\":\"https:\\\/\\\/salonforall.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/salonforall.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/#organization\",\"name\":\"Salon For All B.V. Espa\u00f1a\",\"alternateName\":\"Salon For All B.V. Espa\u00f1a - Mayorista de equipamiento para consultas, salones y suministros\",\"url\":\"https:\\\/\\\/salonforall.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/salonforall.es\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-salon-for-all-e1764543185849.png\",\"contentUrl\":\"https:\\\/\\\/salonforall.es\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-salon-for-all-e1764543185849.png\",\"width\":500,\"height\":150,\"caption\":\"Salon For All B.V. Espa\u00f1a\"},\"image\":{\"@id\":\"https:\\\/\\\/salonforall.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aquecedor de cera Iwax Diamond Preto Comprar","description":"Comprar Iwax Wax Heater Diamond Black online ou no showroom da Salon For ALL Espanha. O grossista para sal\u00f5es, consult\u00f3rios e spas em Espanha e Portugal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/salonforall.es\/pt\/aquecedor-de-cera-iwax-diamante-preto\/","og_locale":"pt_PT","og_type":"article","og_title":"Calentador De Cera Iwax Diamond Negro","og_description":"Compra Calentador De Cera Iwax Diamond Negro online o en el showroom en Salon For ALL Espa\u00f1a. El mayorista para salones, consultas y spas en Espa\u00f1a y Portugal.","og_url":"https:\/\/salonforall.es\/pt\/aquecedor-de-cera-iwax-diamante-preto\/","og_site_name":"Salon For ALL Espa\u00f1a","article_modified_time":"2026-03-24T16:04:36+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/Calentador-De-Cera-Iwax-Diamond-Negro.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Calentador De Cera Iwax Diamond Negro","twitter_misc":{"Tempo estimado de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/salonforall.es\/calentador-de-cera-iwax-diamond-negro\/","url":"https:\/\/salonforall.es\/calentador-de-cera-iwax-diamond-negro\/","name":"Aquecedor de cera Iwax Diamond Preto Comprar","isPartOf":{"@id":"https:\/\/salonforall.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/salonforall.es\/calentador-de-cera-iwax-diamond-negro\/#primaryimage"},"image":{"@id":"https:\/\/salonforall.es\/calentador-de-cera-iwax-diamond-negro\/#primaryimage"},"thumbnailUrl":"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/Calentador-De-Cera-Iwax-Diamond-Negro.jpg","datePublished":"2025-12-02T12:30:48+00:00","dateModified":"2026-03-24T16:04:36+00:00","description":"Comprar Iwax Wax Heater Diamond Black online ou no showroom da Salon For ALL Espanha. O grossista para sal\u00f5es, consult\u00f3rios e spas em Espanha e Portugal.","breadcrumb":{"@id":"https:\/\/salonforall.es\/calentador-de-cera-iwax-diamond-negro\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/salonforall.es\/calentador-de-cera-iwax-diamond-negro\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/salonforall.es\/calentador-de-cera-iwax-diamond-negro\/#primaryimage","url":"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/Calentador-De-Cera-Iwax-Diamond-Negro.jpg","contentUrl":"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/Calentador-De-Cera-Iwax-Diamond-Negro.jpg","width":1200,"height":1200,"caption":"Calentador De Cera Iwax Diamond Negro"},{"@type":"BreadcrumbList","@id":"https:\/\/salonforall.es\/calentador-de-cera-iwax-diamond-negro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/salonforall.es\/"},{"@type":"ListItem","position":2,"name":"Winkel","item":"https:\/\/salonforall.es\/winkel\/"},{"@type":"ListItem","position":3,"name":"Calentador De Cera Iwax Diamond Negro"}]},{"@type":"WebSite","@id":"https:\/\/salonforall.es\/#website","url":"https:\/\/salonforall.es\/","name":"Sal\u00e3o de beleza para toda a Espanha","description":"Grossista de mobili\u00e1rio e material para sal\u00f5es de beleza e consult\u00f3rios","publisher":{"@id":"https:\/\/salonforall.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/salonforall.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/salonforall.es\/#organization","name":"Salon For All B.V. Espanha","alternateName":"Salon For All B.V. Espa\u00f1a - Mayorista de equipamiento para consultas, salones y suministros","url":"https:\/\/salonforall.es\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/salonforall.es\/#\/schema\/logo\/image\/","url":"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/11\/logo-salon-for-all-e1764543185849.png","contentUrl":"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/11\/logo-salon-for-all-e1764543185849.png","width":500,"height":150,"caption":"Salon For All B.V. Espa\u00f1a"},"image":{"@id":"https:\/\/salonforall.es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/salonforall.es\/pt\/wp-json\/wp\/v2\/product\/11246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salonforall.es\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/salonforall.es\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/salonforall.es\/pt\/wp-json\/wp\/v2\/comments?post=11246"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/salonforall.es\/pt\/wp-json\/wp\/v2\/media\/11247"}],"wp:attachment":[{"href":"https:\/\/salonforall.es\/pt\/wp-json\/wp\/v2\/media?parent=11246"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/salonforall.es\/pt\/wp-json\/wp\/v2\/product_brand?post=11246"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/salonforall.es\/pt\/wp-json\/wp\/v2\/product_cat?post=11246"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/salonforall.es\/pt\/wp-json\/wp\/v2\/product_tag?post=11246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}