{"id":10532,"date":"2025-12-02T13:21:41","date_gmt":"2025-12-02T12:21:41","guid":{"rendered":"https:\/\/salonforall.es\/product\/el-cartel-cartuchos-de-tatuaje-0-35-45-soft-edge-magnum-10-uds\/"},"modified":"2026-03-24T17:01:16","modified_gmt":"2026-03-24T16:01:16","slug":"el-cartel-cartuchos-de-tatuaje-0-35-45-soft-edge-magnum-10-uds","status":"publish","type":"product","link":"https:\/\/salonforall.es\/en\/el-cartel-cartuchos-de-tatuaje-0-35-45-soft-edge-magnum-10-uds\/","title":{"rendered":"El Cartel Cartuchos De Tatuaje 0.35 45 Soft Edge Magnum 10 Uds."},"content":{"rendered":"<h2>Informaci\u00f3n sobre El Cartel Cartuchos De Tatuaje 0.35 45 Soft Edge Magnum 10 Uds. con n\u00famero de art\u00edculo 144051<\/h2>\n<p>EL CARTEL was founded to provide high quality needles to the most demanding tattooists. QUALITY MATTERS. Thanks to new technology, high quality materials and strict quality control, EL CARTEL created state-of-the-art tattoo cartridges. SAFETY FIRST. For safety and hygiene reasons, EL CARTEL uses elastic and durable membranes in the cartridges to prevent ink or blood from leaking into the machine. The new shape of the tube allows more ink to be stored, which increases efficiency. Thanks to the high quality materials, our needles guarantee a smooth ink injection and stay sharp during long tattooing sessions. All cartridges are sterile and have a shelf life of up to 5 years. They are compatible with any machine with a handle.<\/p>\n<p>Los productos Activeshop son proporcionalmente m\u00e1s econ\u00f3micos que muchas otras marcas\/proveedores. El precio est\u00e1 en relaci\u00f3n con la calidad. El Cartel Cartuchos De Tatuaje 0.35 45 Soft Edge Magnum 10 Uds. es por lo tanto una soluci\u00f3n accesible para su sal\u00f3n.<\/p>\n<h2>\u00bfC\u00f3mo se entrega El Cartel Cartuchos De Tatuaje 0.35 45 Soft Edge Magnum 10 Uds.?<\/h2>\n<p>El Cartel Cartuchos De Tatuaje 0.35 45 Soft Edge Magnum 10 Uds. se entrega en embalaje(s) original(es). Dentro de Espa\u00f1a el env\u00edo de El Cartel Cartuchos De Tatuaje 0.35 45 Soft Edge Magnum 10 Uds. es completamente gratuito para pedidos a partir de 100,- euros. Para env\u00edos a otros pa\u00edses se aplican tarifas de env\u00edo separadas. Puede consultar estas tarifas con nosotros o verlas en el carrito de compra. El Cartel Cartuchos De Tatuaje 0.35 45 Soft Edge Magnum 10 Uds. se env\u00eda a trav\u00e9s de un servicio de mensajer\u00eda externo.<\/p>\n<p>Packages or pallets are delivered as standard up to the front door threshold, even if you are located in a collective building, apartment building or apartment complex with a lift (provided the item fits in the lift). No lift available or item does not fit in the lift? Then we deliver up to the threshold of the ground floor.<\/p>\n<p>Do you still have questions about delivery or a special situation? Contact us and we will be happy to help you!<\/p>\n<p>*Items are not unpacked or assembled as standard. In special situations you can contact us to make arrangements.<\/p>\n<h2>Secure online shopping at Salon For All with the Webwinkelkeur seal of quality and SSL encryption.<\/h2>\n<p>Es importante para nosotros que nuestros clientes puedan comprar de forma segura en nuestra tienda online. Estamos afiliados al sello de calidad nacional Webwinkelkeur desde 2019. Nuestra identidad ha sido verificada y comprobada por ellos, y la tienda online ha sido revisada y aprobada legalmente. Adem\u00e1s, nuestra tienda online est\u00e1 afiliada a ellos para la mediaci\u00f3n de conflictos. Puede ver la insignia con toda la informaci\u00f3n de este sello de calidad de tienda online en el lado izquierdo o derecho de la tienda online (bot\u00f3n rosa con blanco). Adem\u00e1s, nuestro sitio est\u00e1 protegido con un certificado SSL para que pueda navegar de forma segura con nosotros. En la barra de su navegador de Internet, donde aparece nuestro sitio web, ver\u00e1 un icono de candado. Si hace clic en el candado, obtendr\u00e1 toda la informaci\u00f3n sobre nuestra seguridad. De esta manera sabe que su pedido de El Cartel Cartuchos De Tatuaje 0.35 45 Soft Edge Magnum 10 Uds. y sus datos personales se procesan de forma segura.<\/p>\n<h2>\u00bfC\u00f3mo puedo pagar El Cartel Cartuchos De Tatuaje 0.35 45 Soft Edge Magnum 10 Uds.?<\/h2>\n<p>We want to make it as easy as possible for you. That's why at Salon For All you can pay with all popular payment methods. Pay in advance, on delivery or afterwards - everything is possible. See here for all the payment methods we offer:<\/p>\n<ul>\n<li>iDEAL<\/li>\n<li>Credit card (Visa, Mastercard, American Express)<\/li>\n<li>Klarna - Payment on delivery with invoice<\/li>\n<li>PayPal<\/li>\n<li>Apple Pay<\/li>\n<li>Google Pay<\/li>\n<li>Bizum (for Spanish customers)<\/li>\n<li>SEPA bank transfer<\/li>\n<li>Bancontact<\/li>\n<li>Commercial invoice for companies<\/li>\n<li>Payment in the showroom - Both card and cash (Only available on collection)<\/li>\n<\/ul>\n<h2>See also reviews of Salon For All<\/h2>\n<p>Consulte tambi\u00e9n nuestras rese\u00f1as para tener en cuenta las experiencias de nuestros clientes actuales en su decisi\u00f3n de pedir El Cartel Cartuchos De Tatuaje 0.35 45 Soft Edge Magnum 10 Uds. con nosotros. A trav\u00e9s de nuestro sello de calidad independiente de tienda online Webwinkelkeur, se recopilan autom\u00e1ticamente rese\u00f1as verificadas de clientes que han completado un pedido con nosotros. Puede encontrarlas detr\u00e1s del bot\u00f3n rosa en nuestra tienda online o aparecen listadas debajo de los productos.<\/p>\n<p>\u00a1Comparta tambi\u00e9n su experiencia despu\u00e9s de su compra con su El Cartel Cartuchos De Tatuaje 0.35 45 Soft Edge Magnum 10 Uds. pedido y su experiencia con el proceso de compra o el contacto con Salon For All para inspirar a otros!<\/p>\n<h2>Contact Salon For All<\/h2>\n<p>Cont\u00e1ctenos entonces. Estaremos encantados de ayudarle con la adquisici\u00f3n de El Cartel Cartuchos De Tatuaje 0.35 45 Soft Edge Magnum 10 Uds.. En d\u00edas laborables estamos mejor disponibles entre las 8.30 y las 17.00 horas a trav\u00e9s del n\u00famero de tel\u00e9fono y direcci\u00f3n de correo electr\u00f3nico en la parte superior de la tienda online o a trav\u00e9s de la funci\u00f3n de chat. Las consultas fuera del horario de oficina suelen responderse en un plazo de 24 horas. Tambi\u00e9n es posible visitarnos fuera de los d\u00edas laborables u horario de oficina. Pero para ello es necesario concertar una cita previa.<\/p>\n<h2>Would you like to visit our showroom?<\/h2>\n<p>\u00bfPrefiere ver El Cartel Cartuchos De Tatuaje 0.35 45 Soft Edge Magnum 10 Uds. o recorrer nuestra oferta de la tienda (online) junto con nuestro colega? Entonces visite nuestro showroom con m\u00e1s de 1000m\u00b2 de equipamiento para salones y d\u00e9jese inspirar por nuestros empleados. Tambi\u00e9n si le gusta conocernos de manera agradable disfrutando de una buena taza de caf\u00e9 o t\u00e9, es muy bienvenido. No tenemos todos los productos en stock, as\u00ed que h\u00e1ganos saber de antemano que desea venir. Concierte siempre una cita previa.<\/p>\n<h2>14 days of reflection and our return policy<\/h2>\n<p>Por supuesto puede ocurrir que El Cartel Cartuchos De Tatuaje 0.35 45 Soft Edge Magnum 10 Uds. entregado no sea completamente de su agrado y desee devolverlo. Eso no es ning\u00fan problema en Salon For All. Debe notificar su devoluci\u00f3n dentro de 14 d\u00edas laborables a trav\u00e9s de info@salonforall.es. Entonces recibir\u00e1 primero todas las instrucciones y condiciones de devoluci\u00f3n. Tenga en cuenta que El Cartel Cartuchos De Tatuaje 0.35 45 Soft Edge Magnum 10 Uds. no debe haber sido usado, debe contener todas las partes suministradas y debe devolverse empaquetado en el embalaje original. Los costos de env\u00edo de una devoluci\u00f3n son siempre a cargo del comprador en compras a trav\u00e9s de www.salonforall.es. Debe organizar usted mismo un transporte con una empresa de transporte de su elecci\u00f3n para una devoluci\u00f3n. Una vez que El Cartel Cartuchos De Tatuaje 0.35 45 Soft Edge Magnum 10 Uds. haya sido devuelto, se verificar\u00e1 su integridad y posibles da\u00f1os. Una vez que la devoluci\u00f3n haya sido aprobada, el importe de la compra se reembolsar\u00e1 dentro de 5 d\u00edas laborables a la cuenta bancaria que tenemos registrada.<\/p>\n<h2>Who is Salon For All?<\/h2>\n<p>Salon For All is THE wholesaler for all salon equipment in Europe. Salon For All started in 2003 under the name Salonvoordeel and grew out of practice. The owners of Salon For All were experienced hairdressers and beauty specialists and have together more than 30 years of practical experience. In 2003 we launched Salonvoordeel.nl (Netherlands) and subsequently Salon For All was founded for the European market. Some of our employees started their own business and so the idea to launch a functional online shop for hairdressers and to help them with the equipment of their salon was born.<\/p>\n<p>Nuestro showroom se encuentra en Dinxperlo, directamente en la frontera entre los Pa\u00edses Bajos y Alemania. Con nuestra amplia experiencia en el sector podemos servirle de espejo y proporcionarle el asesoramiento adecuado. \u00a1Hablamos el mismo idioma! Le asesoramos, inspiramos, motivamos y ayudamos en la adquisici\u00f3n de El Cartel Cartuchos De Tatuaje 0.35 45 Soft Edge Magnum 10 Uds.. Nuestros proveedores se encuentran en toda Europa, desde Alemania, Inglaterra, Italia hasta Polonia.<\/p>","protected":false},"excerpt":{"rendered":"<p>El producto El Cartel Cartuchos De Tatuaje 0.35 45 Soft Edge Magnum 10 Uds. es una soluci\u00f3n de alta calidad para cualquier sal\u00f3n. El plazo de entrega estimado es de aproximadamente 6 d\u00edas laborables.<\/p>","protected":false},"featured_media":10533,"comment_status":"open","ping_status":"open","template":"","meta":[],"product_brand":[3025],"product_cat":[3027,3026,3036],"product_tag":[3030,3029,3037],"class_list":{"0":"post-10532","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-el-cartel","7":"product_cat-agujas-de-tatuaje-cartuchos","8":"product_cat-equipos-para-estudios-de-tatuaje","9":"product_cat-sem-cartucho-magnum-de-borde-suave","10":"product_tag-agujas-de-tatuaje-cartuchos","11":"product_tag-equipos-para-estudios-de-tatuaje","12":"product_tag-sem-cartucho-magnum-de-borde-suave","13":"pa_codigo-ean-7759","14":"pa_garantia-12-meses","15":"pa_marca-el-cartel","16":"pa_numero-de-articulo-4297","17":"pa_tiempo-estimado-de-entrega-4-5-dias-laborables","19":"first","20":"instock","21":"sale","22":"taxable","23":"shipping-taxable","24":"purchasable","25":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Cartel Cartuchos De Tatuaje 0.35 45 Soft Edge Magnum 10 Uds. comprar<\/title>\n<meta name=\"description\" content=\"Compra El Cartel Cartuchos De Tatuaje 0.35 45 Soft Edge Magnum 10 Uds. online o en el showroom en Salon For ALL Espa\u00f1a. El mayorista para salones, consultas y spas en Espa\u00f1a y Portugal.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/salonforall.es\/en\/el-cartel-cartuchos-de-tatuaje-0-35-45-soft-edge-magnum-10-uds\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Cartel Cartuchos De Tatuaje 0.35 45 Soft Edge Magnum 10 Uds.\" \/>\n<meta property=\"og:description\" content=\"Compra El Cartel Cartuchos De Tatuaje 0.35 45 Soft Edge Magnum 10 Uds. online o en el showroom en Salon For ALL Espa\u00f1a. El mayorista para salones, consultas y spas en Espa\u00f1a y Portugal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/salonforall.es\/en\/el-cartel-cartuchos-de-tatuaje-0-35-45-soft-edge-magnum-10-uds\/\" \/>\n<meta property=\"og:site_name\" content=\"Salon For ALL Espa\u00f1a\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-24T16:01:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/El-Cartel-Cartuchos-De-Tatuaje-0.35-45-Soft-Edge-Magnum-10-Uds.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"El Cartel Cartuchos De Tatuaje 0.35 45 Soft Edge Magnum 10 Uds.\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/el-cartel-cartuchos-de-tatuaje-0-35-45-soft-edge-magnum-10-uds\\\/\",\"url\":\"https:\\\/\\\/salonforall.es\\\/el-cartel-cartuchos-de-tatuaje-0-35-45-soft-edge-magnum-10-uds\\\/\",\"name\":\"El Cartel Cartuchos De Tatuaje 0.35 45 Soft Edge Magnum 10 Uds. comprar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/salonforall.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/salonforall.es\\\/el-cartel-cartuchos-de-tatuaje-0-35-45-soft-edge-magnum-10-uds\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/salonforall.es\\\/el-cartel-cartuchos-de-tatuaje-0-35-45-soft-edge-magnum-10-uds\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/salonforall.es\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/El-Cartel-Cartuchos-De-Tatuaje-0.35-45-Soft-Edge-Magnum-10-Uds.jpg\",\"datePublished\":\"2025-12-02T12:21:41+00:00\",\"dateModified\":\"2026-03-24T16:01:16+00:00\",\"description\":\"Compra El Cartel Cartuchos De Tatuaje 0.35 45 Soft Edge Magnum 10 Uds. online o en el showroom en Salon For ALL Espa\u00f1a. El mayorista para salones, consultas y spas en Espa\u00f1a y Portugal.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/salonforall.es\\\/el-cartel-cartuchos-de-tatuaje-0-35-45-soft-edge-magnum-10-uds\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/salonforall.es\\\/el-cartel-cartuchos-de-tatuaje-0-35-45-soft-edge-magnum-10-uds\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/el-cartel-cartuchos-de-tatuaje-0-35-45-soft-edge-magnum-10-uds\\\/#primaryimage\",\"url\":\"https:\\\/\\\/salonforall.es\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/El-Cartel-Cartuchos-De-Tatuaje-0.35-45-Soft-Edge-Magnum-10-Uds.jpg\",\"contentUrl\":\"https:\\\/\\\/salonforall.es\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/El-Cartel-Cartuchos-De-Tatuaje-0.35-45-Soft-Edge-Magnum-10-Uds.jpg\",\"width\":1200,\"height\":1200,\"caption\":\"El Cartel Cartuchos De Tatuaje 0.35 45 Soft Edge Magnum 10 Uds.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/el-cartel-cartuchos-de-tatuaje-0-35-45-soft-edge-magnum-10-uds\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/salonforall.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Winkel\",\"item\":\"https:\\\/\\\/salonforall.es\\\/winkel\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"El Cartel Cartuchos De Tatuaje 0.35 45 Soft Edge Magnum 10 Uds.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/#website\",\"url\":\"https:\\\/\\\/salonforall.es\\\/\",\"name\":\"Salon For ALL Espa\u00f1a\",\"description\":\"Mayorista de mobiliario y suministros para consultorios y salones\",\"publisher\":{\"@id\":\"https:\\\/\\\/salonforall.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/salonforall.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/#organization\",\"name\":\"Salon For All B.V. Espa\u00f1a\",\"alternateName\":\"Salon For All B.V. Espa\u00f1a - Mayorista de equipamiento para consultas, salones y suministros\",\"url\":\"https:\\\/\\\/salonforall.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/salonforall.es\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-salon-for-all-e1764543185849.png\",\"contentUrl\":\"https:\\\/\\\/salonforall.es\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-salon-for-all-e1764543185849.png\",\"width\":500,\"height\":150,\"caption\":\"Salon For All B.V. Espa\u00f1a\"},\"image\":{\"@id\":\"https:\\\/\\\/salonforall.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Cartel Cartuchos De Tatuaje 0.35 45 Soft Edge Magnum 10 Uds. comprar","description":"Compra El Cartel Cartuchos De Tatuaje 0.35 45 Soft Edge Magnum 10 Uds. online o en el showroom en Salon For ALL Espa\u00f1a. El mayorista para salones, consultas y spas en Espa\u00f1a y Portugal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/salonforall.es\/en\/el-cartel-cartuchos-de-tatuaje-0-35-45-soft-edge-magnum-10-uds\/","og_locale":"en_GB","og_type":"article","og_title":"El Cartel Cartuchos De Tatuaje 0.35 45 Soft Edge Magnum 10 Uds.","og_description":"Compra El Cartel Cartuchos De Tatuaje 0.35 45 Soft Edge Magnum 10 Uds. online o en el showroom en Salon For ALL Espa\u00f1a. El mayorista para salones, consultas y spas en Espa\u00f1a y Portugal.","og_url":"https:\/\/salonforall.es\/en\/el-cartel-cartuchos-de-tatuaje-0-35-45-soft-edge-magnum-10-uds\/","og_site_name":"Salon For ALL Espa\u00f1a","article_modified_time":"2026-03-24T16:01:16+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/El-Cartel-Cartuchos-De-Tatuaje-0.35-45-Soft-Edge-Magnum-10-Uds.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"El Cartel Cartuchos De Tatuaje 0.35 45 Soft Edge Magnum 10 Uds.","twitter_misc":{"Estimated reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/salonforall.es\/el-cartel-cartuchos-de-tatuaje-0-35-45-soft-edge-magnum-10-uds\/","url":"https:\/\/salonforall.es\/el-cartel-cartuchos-de-tatuaje-0-35-45-soft-edge-magnum-10-uds\/","name":"El Cartel Cartuchos De Tatuaje 0.35 45 Soft Edge Magnum 10 Uds. comprar","isPartOf":{"@id":"https:\/\/salonforall.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/salonforall.es\/el-cartel-cartuchos-de-tatuaje-0-35-45-soft-edge-magnum-10-uds\/#primaryimage"},"image":{"@id":"https:\/\/salonforall.es\/el-cartel-cartuchos-de-tatuaje-0-35-45-soft-edge-magnum-10-uds\/#primaryimage"},"thumbnailUrl":"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/El-Cartel-Cartuchos-De-Tatuaje-0.35-45-Soft-Edge-Magnum-10-Uds.jpg","datePublished":"2025-12-02T12:21:41+00:00","dateModified":"2026-03-24T16:01:16+00:00","description":"Compra El Cartel Cartuchos De Tatuaje 0.35 45 Soft Edge Magnum 10 Uds. online o en el showroom en Salon For ALL Espa\u00f1a. El mayorista para salones, consultas y spas en Espa\u00f1a y Portugal.","breadcrumb":{"@id":"https:\/\/salonforall.es\/el-cartel-cartuchos-de-tatuaje-0-35-45-soft-edge-magnum-10-uds\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/salonforall.es\/el-cartel-cartuchos-de-tatuaje-0-35-45-soft-edge-magnum-10-uds\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/salonforall.es\/el-cartel-cartuchos-de-tatuaje-0-35-45-soft-edge-magnum-10-uds\/#primaryimage","url":"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/El-Cartel-Cartuchos-De-Tatuaje-0.35-45-Soft-Edge-Magnum-10-Uds.jpg","contentUrl":"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/El-Cartel-Cartuchos-De-Tatuaje-0.35-45-Soft-Edge-Magnum-10-Uds.jpg","width":1200,"height":1200,"caption":"El Cartel Cartuchos De Tatuaje 0.35 45 Soft Edge Magnum 10 Uds."},{"@type":"BreadcrumbList","@id":"https:\/\/salonforall.es\/el-cartel-cartuchos-de-tatuaje-0-35-45-soft-edge-magnum-10-uds\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/salonforall.es\/"},{"@type":"ListItem","position":2,"name":"Winkel","item":"https:\/\/salonforall.es\/winkel\/"},{"@type":"ListItem","position":3,"name":"El Cartel Cartuchos De Tatuaje 0.35 45 Soft Edge Magnum 10 Uds."}]},{"@type":"WebSite","@id":"https:\/\/salonforall.es\/#website","url":"https:\/\/salonforall.es\/","name":"Salon For ALL Spain","description":"Wholesaler of salon and practice furniture and supplies","publisher":{"@id":"https:\/\/salonforall.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/salonforall.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/salonforall.es\/#organization","name":"Salon For All B.V. Spain","alternateName":"Salon For All B.V. Espa\u00f1a - Mayorista de equipamiento para consultas, salones y suministros","url":"https:\/\/salonforall.es\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/salonforall.es\/#\/schema\/logo\/image\/","url":"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/11\/logo-salon-for-all-e1764543185849.png","contentUrl":"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/11\/logo-salon-for-all-e1764543185849.png","width":500,"height":150,"caption":"Salon For All B.V. Espa\u00f1a"},"image":{"@id":"https:\/\/salonforall.es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/salonforall.es\/en\/wp-json\/wp\/v2\/product\/10532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salonforall.es\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/salonforall.es\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/salonforall.es\/en\/wp-json\/wp\/v2\/comments?post=10532"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/salonforall.es\/en\/wp-json\/wp\/v2\/media\/10533"}],"wp:attachment":[{"href":"https:\/\/salonforall.es\/en\/wp-json\/wp\/v2\/media?parent=10532"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/salonforall.es\/en\/wp-json\/wp\/v2\/product_brand?post=10532"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/salonforall.es\/en\/wp-json\/wp\/v2\/product_cat?post=10532"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/salonforall.es\/en\/wp-json\/wp\/v2\/product_tag?post=10532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}