{"id":19,"count":2,"description":"","link":"https:\/\/salonforall.es\/en\/category\/decoration\/","name":"Decoration","slug":"decoration","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Decoration Archieven - Salon For ALL Espa\u00f1a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/salonforall.es\/en\/category\/decoration\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Decoration Archieven - Salon For ALL Espa\u00f1a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/salonforall.es\/en\/category\/decoration\/\" \/>\n<meta property=\"og:site_name\" content=\"Salon For ALL Espa\u00f1a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/category\\\/decoration\\\/\",\"url\":\"https:\\\/\\\/salonforall.es\\\/category\\\/decoration\\\/\",\"name\":\"Decoration Archieven - Salon For ALL Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/salonforall.es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/salonforall.es\\\/category\\\/decoration\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/category\\\/decoration\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/salonforall.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Decoration\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/#website\",\"url\":\"https:\\\/\\\/salonforall.es\\\/\",\"name\":\"Salon For ALL Espa\u00f1a\",\"description\":\"Mayorista de mobiliario y suministros para consultorios y salones\",\"publisher\":{\"@id\":\"https:\\\/\\\/salonforall.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/salonforall.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/#organization\",\"name\":\"Salon For All B.V. Espa\u00f1a\",\"alternateName\":\"Salon For All B.V. Espa\u00f1a - Mayorista de equipamiento para consultas, salones y suministros\",\"url\":\"https:\\\/\\\/salonforall.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/salonforall.es\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-salon-for-all-e1764543185849.png\",\"contentUrl\":\"https:\\\/\\\/salonforall.es\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-salon-for-all-e1764543185849.png\",\"width\":500,\"height\":150,\"caption\":\"Salon For All B.V. Espa\u00f1a\"},\"image\":{\"@id\":\"https:\\\/\\\/salonforall.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Decoration Archieven - Salon For ALL Espa\u00f1a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/salonforall.es\/en\/category\/decoration\/","og_locale":"en_GB","og_type":"article","og_title":"Decoration Archieven - Salon For ALL Espa\u00f1a","og_url":"https:\/\/salonforall.es\/en\/category\/decoration\/","og_site_name":"Salon For ALL Espa\u00f1a","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/salonforall.es\/category\/decoration\/","url":"https:\/\/salonforall.es\/category\/decoration\/","name":"Decoration Archieven - Salon For ALL Espa\u00f1a","isPartOf":{"@id":"https:\/\/salonforall.es\/#website"},"breadcrumb":{"@id":"https:\/\/salonforall.es\/category\/decoration\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/salonforall.es\/category\/decoration\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/salonforall.es\/"},{"@type":"ListItem","position":2,"name":"Decoration"}]},{"@type":"WebSite","@id":"https:\/\/salonforall.es\/#website","url":"https:\/\/salonforall.es\/","name":"Salon For ALL Spain","description":"Wholesaler of salon and practice furniture and supplies","publisher":{"@id":"https:\/\/salonforall.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/salonforall.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/salonforall.es\/#organization","name":"Salon For All B.V. Spain","alternateName":"Salon For All B.V. Espa\u00f1a - Mayorista de equipamiento para consultas, salones y suministros","url":"https:\/\/salonforall.es\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/salonforall.es\/#\/schema\/logo\/image\/","url":"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/11\/logo-salon-for-all-e1764543185849.png","contentUrl":"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/11\/logo-salon-for-all-e1764543185849.png","width":500,"height":150,"caption":"Salon For All B.V. Espa\u00f1a"},"image":{"@id":"https:\/\/salonforall.es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/salonforall.es\/en\/wp-json\/wp\/v2\/categories\/19","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salonforall.es\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/salonforall.es\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/salonforall.es\/en\/wp-json\/wp\/v2\/posts?categories=19"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}