{"id":3538,"count":2,"description":"","link":"https:\/\/salonforall.es\/ca\/equipamiento-de-peluqueria\/mobiliario-de-peluqueria\/sillones-y-lavabos-de-peluqueria\/santiago\/","name":"Santiago","slug":"santiago","taxonomy":"product_cat","parent":98,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Santiago - Salon For ALL Espa\u00f1a<\/title>\n<meta name=\"description\" content=\"Compra tu Santiago en Salon For ALL Espa\u00f1a. El mayorista en Espa\u00f1a y Portugal para cada sal\u00f3n. M\u00e1s de 10.000 productos online.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/salonforall.es\/ca\/equipament-de-perruqueria\/mobiliari-de-perruqueria\/butaques-i-lavabos-de-perruqueria\/santiago\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Santiago - Salon For ALL Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"Compra tu Santiago en Salon For ALL Espa\u00f1a. El mayorista en Espa\u00f1a y Portugal para cada sal\u00f3n. M\u00e1s de 10.000 productos online.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/salonforall.es\/ca\/equipament-de-perruqueria\/mobiliari-de-perruqueria\/butaques-i-lavabos-de-perruqueria\/santiago\/\" \/>\n<meta property=\"og:site_name\" content=\"Salon For ALL Espa\u00f1a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/equipamiento-de-peluqueria\\\/mobiliario-de-peluqueria\\\/sillones-y-lavabos-de-peluqueria\\\/santiago\\\/\",\"url\":\"https:\\\/\\\/salonforall.es\\\/equipamiento-de-peluqueria\\\/mobiliario-de-peluqueria\\\/sillones-y-lavabos-de-peluqueria\\\/santiago\\\/\",\"name\":\"Santiago - Salon For ALL Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/salonforall.es\\\/#website\"},\"description\":\"Compra tu Santiago en Salon For ALL Espa\u00f1a. El mayorista en Espa\u00f1a y Portugal para cada sal\u00f3n. M\u00e1s de 10.000 productos online.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/salonforall.es\\\/equipamiento-de-peluqueria\\\/mobiliario-de-peluqueria\\\/sillones-y-lavabos-de-peluqueria\\\/santiago\\\/#breadcrumb\"},\"inLanguage\":\"ca\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/equipamiento-de-peluqueria\\\/mobiliario-de-peluqueria\\\/sillones-y-lavabos-de-peluqueria\\\/santiago\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/salonforall.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Equipamiento de peluquer\u00eda\",\"item\":\"https:\\\/\\\/salonforall.es\\\/equipamiento-de-peluqueria\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mobiliario de peluquer\u00eda\",\"item\":\"https:\\\/\\\/salonforall.es\\\/equipamiento-de-peluqueria\\\/mobiliario-de-peluqueria\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Sillones y lavabos de peluquer\u00eda\",\"item\":\"https:\\\/\\\/salonforall.es\\\/equipamiento-de-peluqueria\\\/mobiliario-de-peluqueria\\\/sillones-y-lavabos-de-peluqueria\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Santiago\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/#website\",\"url\":\"https:\\\/\\\/salonforall.es\\\/\",\"name\":\"Salon For ALL Espa\u00f1a\",\"description\":\"Mayorista de mobiliario y suministros para consultorios y salones\",\"publisher\":{\"@id\":\"https:\\\/\\\/salonforall.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/salonforall.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/#organization\",\"name\":\"Salon For All B.V. Espa\u00f1a\",\"alternateName\":\"Salon For All B.V. Espa\u00f1a - Mayorista de equipamiento para consultas, salones y suministros\",\"url\":\"https:\\\/\\\/salonforall.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/salonforall.es\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-salon-for-all-e1764543185849.png\",\"contentUrl\":\"https:\\\/\\\/salonforall.es\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-salon-for-all-e1764543185849.png\",\"width\":500,\"height\":150,\"caption\":\"Salon For All B.V. Espa\u00f1a\"},\"image\":{\"@id\":\"https:\\\/\\\/salonforall.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Santiago - Salon For ALL Espanya","description":"Compra el teu Santiago a Salon For ALL Espanya. El majorista a Espanya i Portugal per a cada sal\u00f3. M\u00e9s de 10.000 productes en l\u00ednia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/salonforall.es\/ca\/equipament-de-perruqueria\/mobiliari-de-perruqueria\/butaques-i-lavabos-de-perruqueria\/santiago\/","og_locale":"ca_ES","og_type":"article","og_title":"Santiago - Salon For ALL Espa\u00f1a","og_description":"Compra tu Santiago en Salon For ALL Espa\u00f1a. El mayorista en Espa\u00f1a y Portugal para cada sal\u00f3n. M\u00e1s de 10.000 productos online.","og_url":"https:\/\/salonforall.es\/ca\/equipament-de-perruqueria\/mobiliari-de-perruqueria\/butaques-i-lavabos-de-perruqueria\/santiago\/","og_site_name":"Salon For ALL Espa\u00f1a","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/salonforall.es\/equipamiento-de-peluqueria\/mobiliario-de-peluqueria\/sillones-y-lavabos-de-peluqueria\/santiago\/","url":"https:\/\/salonforall.es\/equipamiento-de-peluqueria\/mobiliario-de-peluqueria\/sillones-y-lavabos-de-peluqueria\/santiago\/","name":"Santiago - Salon For ALL Espanya","isPartOf":{"@id":"https:\/\/salonforall.es\/#website"},"description":"Compra el teu Santiago a Salon For ALL Espanya. El majorista a Espanya i Portugal per a cada sal\u00f3. M\u00e9s de 10.000 productes en l\u00ednia.","breadcrumb":{"@id":"https:\/\/salonforall.es\/equipamiento-de-peluqueria\/mobiliario-de-peluqueria\/sillones-y-lavabos-de-peluqueria\/santiago\/#breadcrumb"},"inLanguage":"ca"},{"@type":"BreadcrumbList","@id":"https:\/\/salonforall.es\/equipamiento-de-peluqueria\/mobiliario-de-peluqueria\/sillones-y-lavabos-de-peluqueria\/santiago\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/salonforall.es\/"},{"@type":"ListItem","position":2,"name":"Equipamiento de peluquer\u00eda","item":"https:\/\/salonforall.es\/equipamiento-de-peluqueria\/"},{"@type":"ListItem","position":3,"name":"Mobiliario de peluquer\u00eda","item":"https:\/\/salonforall.es\/equipamiento-de-peluqueria\/mobiliario-de-peluqueria\/"},{"@type":"ListItem","position":4,"name":"Sillones y lavabos de peluquer\u00eda","item":"https:\/\/salonforall.es\/equipamiento-de-peluqueria\/mobiliario-de-peluqueria\/sillones-y-lavabos-de-peluqueria\/"},{"@type":"ListItem","position":5,"name":"Santiago"}]},{"@type":"WebSite","@id":"https:\/\/salonforall.es\/#website","url":"https:\/\/salonforall.es\/","name":"Salon For ALL Espanya","description":"Majorista de mobiliari i subministraments per a consultoris i salons","publisher":{"@id":"https:\/\/salonforall.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/salonforall.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/salonforall.es\/#organization","name":"Salon For All BV Espanya","alternateName":"Salon For All B.V. Espa\u00f1a - Mayorista de equipamiento para consultas, salones y suministros","url":"https:\/\/salonforall.es\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/salonforall.es\/#\/schema\/logo\/image\/","url":"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/11\/logo-salon-for-all-e1764543185849.png","contentUrl":"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/11\/logo-salon-for-all-e1764543185849.png","width":500,"height":150,"caption":"Salon For All B.V. Espa\u00f1a"},"image":{"@id":"https:\/\/salonforall.es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/salonforall.es\/ca\/wp-json\/wp\/v2\/product_cat\/3538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salonforall.es\/ca\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/salonforall.es\/ca\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/salonforall.es\/ca\/wp-json\/wp\/v2\/product_cat\/98"}],"wp:post_type":[{"href":"https:\/\/salonforall.es\/ca\/wp-json\/wp\/v2\/product?product_cat=3538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}