{"id":384,"date":"2023-06-06T10:59:10","date_gmt":"2023-06-06T10:59:10","guid":{"rendered":"https:\/\/dummy.xtemos.com\/woodmart2\/furniture2\/?page_id=15"},"modified":"2025-12-09T14:32:37","modified_gmt":"2025-12-09T13:32:37","slug":"home-furniture2","status":"publish","type":"page","link":"https:\/\/salonforall.es\/ca\/","title":{"rendered":"Home Salon For All Espa\u00f1a"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div style=\"min-height: 600px\" data-vc-full-width=\"true\" data-vc-full-width-temp=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1765286804627 vc_row-has-fill vc_row-o-content-middle vc_row-flex wd-bg-center-center wd-rs-69382389ec44a\"><div class=\"wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-8 wd-enabled-flex color-scheme-light wd-rs-69381e4dee5b8\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t\t<div id=\"wd-693824ee7c01e\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-693824ee7c01e wd-title-color-default wd-title-style-default text-center  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h1 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-xxl\" >Comer\u00e7 majorista d&#039;equipament per a consultoris, equipament per a salons i accessoris<\/h1>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2 style=\"text-align: center;\">Qu\u00e8 est\u00e0s buscant?<\/h2>\n\n\t\t<\/div>\n\t<\/div>\n\t\t\t<div class=\"wd-el-search wd-wpb woodmart-ajax-search  wd-rs-69381c88d15be wd-color-dark\">\n\t\t\t\t<div class=\"wd-search-form\">\n\n<form role=\"search\" method=\"get\" class=\"searchform  wd-style-default woodmart-ajax-search\" action=\"https:\/\/salonforall.es\/ca\/\"  data-thumbnail=\"1\" data-price=\"1\" data-post_type=\"product\" data-count=\"8\" data-sku=\"0\" data-symbols_count=\"3\" data-include_cat_search=\"no\" autocomplete=\"off\" data-trp-original-action=\"https:\/\/salonforall.es\/ca\/\">\n\t<input type=\"text\" class=\"s\" placeholder=\"Search for products\" value=\"\" name=\"s\" aria-label=\"Search\" title=\"Search for products\" required>\n\t<input type=\"hidden\" name=\"post_type\" value=\"product\">\n\n\t<span tabindex=\"0\" aria-label=\"Clear search\" class=\"wd-clear-search wd-role-btn wd-hide\"><\/span>\n\n\t\n\t<button type=\"submit\" class=\"searchsubmit\">\n\t\t<span>\n\t\t\tSearch\t\t<\/span>\n\t\t\t<\/button>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"ca\"\/><\/form>\n\n\t<div class=\"wd-search-results-wrapper\">\n\t\t<div class=\"wd-search-results wd-dropdown-results wd-dropdown wd-scroll\">\n\t\t\t<div class=\"wd-scroll-content\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t\t<div id=\"wd-6938244f05742\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-6938244f05742 wd-title-color-default wd-title-style-default text-left  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h2 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-l\" >Productes populars<\/h2>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\t\t\t<div class=\"wd-products-element wd-rs-6938246f153d1 wd-wpb\">\n\t\t\t\n\t\t\n\t\t\t\t\t<div class=\"products wd-products  grid-columns-4 elements-grid wd-grid-g wd-loop-builder-off wd-stretch-cont-lg\" data-paged=\"1\" data-atts=\"{&quot;items_per_page&quot;:&quot;8&quot;,&quot;sale_countdown&quot;:&quot;0&quot;,&quot;stock_progress_bar&quot;:&quot;0&quot;,&quot;highlighted_products&quot;:&quot;0&quot;,&quot;products_bordered_grid&quot;:&quot;0&quot;,&quot;products_with_background&quot;:&quot;0&quot;,&quot;products_shadow&quot;:&quot;0&quot;,&quot;woodmart_css_id&quot;:&quot;6938246f153d1&quot;,&quot;force_not_ajax&quot;:&quot;no&quot;}\" data-source=\"shortcode\" data-columns=\"4\" style=\"--wd-col-lg:4;--wd-col-md:4;--wd-col-sm:2;--wd-gap-lg:20px;--wd-gap-sm:10px;\">\n\t\t\t<div class=\"wd-product wd-col wd-hover-buttons-on-hover product-grid-item product type-product post-17488 status-publish instock product_cat-cosmetica-farmona product_cat-cosmetica-profesional product_cat-cuidado-facial-cosmetica-farmona product_cat-pure-icon-desmaquillante-y-limpiador product_tag-cosmetica-farmona product_tag-cosmetica-profesional product_tag-cuidado-facial product_tag-pure-icon-desmaquillante-y-limpiador has-post-thumbnail sale taxable shipping-taxable purchasable product-type-simple\" data-loop=\"1\" data-id=\"17488\">\n\t\n<div class=\"wd-product-wrapper product-wrapper\">\n\t<div class=\"wd-product-thumb product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/salonforall.es\/ca\/value-2\/\" class=\"wd-product-img-link product-image-link\" tabindex=\"-1\" aria-label=\"#VALUE!\">\n\t\t\t\t\t\t<div class=\"product-labels labels-rounded\">\n\t\t\t\t<span class=\"onsale product-label wd-shape-round\">-24%<\/span>\t\t\t<\/div>\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-1-600x600.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"#VALUE!\" srcset=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-1-600x600.jpg 600w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-1-300x300.jpg 300w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-1-1024x1024.jpg 1024w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-1-150x150.jpg 150w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-1-768x768.jpg 768w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-1-12x12.jpg 12w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-1.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/salonforall.es\/ca\/wishlist\/\" data-key=\"ab8c0d4a71\" data-product-id=\"17488\" rel=\"nofollow\">\n\t\t\t\t\t<span class=\"wd-action-icon\">\n\t\t\t\t\t\t<span class=\"wd-check-icon\"><\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom\">\n\n\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/salonforall.es\/ca\/value-2\/\">#VALUE!<\/a><\/h3>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t\t\t\t<a href=\"https:\/\/salonforall.es\/ca\/cosmetica-profesional\/\" rel=\"tag\">Cosm\u00e8tica professional<\/a><span class=\"wd-meta-sep\">,<\/span> <a href=\"https:\/\/salonforall.es\/ca\/cosmetica-profesional\/cosmetica-farmona\/\" rel=\"tag\">Cosm\u00e8tica FARMONA<\/a><span class=\"wd-meta-sep\">,<\/span> <a href=\"https:\/\/salonforall.es\/ca\/cosmetica-profesional\/cosmetica-farmona\/cuidado-facial-cosmetica-farmona\/\" rel=\"tag\">Cura facial<\/a><span class=\"wd-meta-sep\">,<\/span> <a href=\"https:\/\/salonforall.es\/ca\/cosmetica-profesional\/cosmetica-farmona\/cuidado-facial-cosmetica-farmona\/pure-icon-desmaquillante-y-limpiador\/\" rel=\"tag\">PURE ICON Desmaquillant i netejador<\/a>\t\t<\/div>\n\t\t\n\t\t\n\t\t<div class=\"wrap-price\">\n\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>14,44<span class=\"woocommerce-Price-currencySymbol\">\u20ac<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">El preu original era: 14,44&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>10,96<span class=\"woocommerce-Price-currencySymbol\">\u20ac<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">El preu actual \u00e9s: 10,96&euro;.<\/span> <small class=\"woocommerce-price-suffix\">IVA excl\u00f2s<\/small><\/span>\n\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t<div class=\"wd-product-footer\">\n\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t<a href=\"\/ca\/wp-json\/wp\/v2\/pages\/384?add-to-cart=17488\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_17488\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"17488\" data-product_sku=\"151833\" aria-label=\"Afegeix a la cistella: \u201c#VALUE!\u201d\" rel=\"nofollow\" data-success_message=\"\u201c#VALUE!\u201d s&#039;ha afegit a la vostra cistella\" role=\"button\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span class=\"wd-action-icon\"><span class=\"wd-check-icon\"><\/span><\/span><span class=\"wd-action-text\" data-no-translation=\"\" data-trp-gettext=\"\">Afegeix a la cistella<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_17488\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t<div class=\"wd-action-buttons\">\n\t\t\t\t\t\t<div class=\"wd-compare-btn wd-action-btn wd-style-icon wd-compare-icon wd-tooltip\">\n\t\t\t<a href=\"https:\/\/salonforall.es\/ca\/compare\/\" class=\"\" data-id=\"17488\" rel=\"nofollow\">\n\t\t\t\t<span class=\"wd-action-icon\">\n\t\t\t\t\t<span class=\"wd-check-icon\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class=\"wd-action-text\">Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-quick-view-btn wd-quick-view-icon wd-action-btn wd-style-icon wd-tooltip\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/salonforall.es\/ca\/value-2\/\"\n\t\t\t\tclass=\"open-quick-view\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"17488\"\n\t\t\t\t>\n\t\t\t\t\t<span class=\"wd-action-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">\n\t\t\t\t\t\tQuick view\t\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"wd-product wd-col wd-hover-buttons-on-hover product-grid-item product type-product post-13897 status-publish instock product_cat-bases-y-tops-hibridos product_cat-manicura-hibrida-claresa product_tag-bases-y-tops-hibridos product_tag-manicura-hibrida-claresa has-post-thumbnail sale taxable shipping-taxable purchasable product-type-simple\" data-loop=\"2\" data-id=\"13897\">\n\t\n<div class=\"wd-product-wrapper product-wrapper\">\n\t<div class=\"wd-product-thumb product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/salonforall.es\/ca\/value\/\" class=\"wd-product-img-link product-image-link\" tabindex=\"-1\" aria-label=\"#VALUE!\">\n\t\t\t\t\t<div class=\"wd-product-grid-slider wd-fill wd-hide-lg\">\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-600x600.jpg\" data-image-srcset=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-600x600.jpg 600w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-300x300.jpg 300w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-1024x1024.jpg 1024w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-150x150.jpg 150w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-768x768.jpg 768w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-12x12.jpg 12w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE.jpg 1200w\" data-image-id=\"0\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-2-600x600.jpg\" data-image-srcset=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-2-600x600.jpg 600w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-2-300x300.jpg 300w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-2-1024x1024.jpg 1024w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-2-150x150.jpg 150w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-2-768x768.jpg 768w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-2-12x12.jpg 12w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-2.jpg 1200w\" data-image-id=\"1\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-4-600x600.jpg\" data-image-srcset=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-4-600x600.jpg 600w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-4-300x300.jpg 300w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-4-1024x1024.jpg 1024w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-4-150x150.jpg 150w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-4-768x768.jpg 768w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-4-12x12.jpg 12w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-4.jpg 1200w\" data-image-id=\"2\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-6-600x600.jpg\" data-image-srcset=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-6-600x600.jpg 600w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-6-300x300.jpg 300w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-6-1024x1024.jpg 1024w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-6-150x150.jpg 150w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-6-768x768.jpg 768w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-6-12x12.jpg 12w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-6.jpg 1200w\" data-image-id=\"3\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-8-600x600.jpg\" data-image-srcset=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-8-600x600.jpg 600w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-8-300x300.jpg 300w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-8-1024x1024.jpg 1024w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-8-150x150.jpg 150w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-8-768x768.jpg 768w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-8-12x12.jpg 12w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-8.jpg 1200w\" data-image-id=\"4\"><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-product-grid-slider-nav wd-fill wd-hide-md\">\n\t\t\t\t<div class=\"wd-prev\"><\/div>\n\t\t\t\t<div class=\"wd-next\"><\/div>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"product-labels labels-rounded\">\n\t\t\t\t<span class=\"onsale product-label wd-shape-round\">-24%<\/span>\t\t\t<\/div>\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-600x600.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"#VALUE!\" srcset=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-600x600.jpg 600w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-300x300.jpg 300w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-1024x1024.jpg 1024w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-150x150.jpg 150w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-768x768.jpg 768w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE-12x12.jpg 12w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/VALUE.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/salonforall.es\/ca\/wishlist\/\" data-key=\"ab8c0d4a71\" data-product-id=\"13897\" rel=\"nofollow\">\n\t\t\t\t\t<span class=\"wd-action-icon\">\n\t\t\t\t\t\t<span class=\"wd-check-icon\"><\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom\">\n\n\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/salonforall.es\/ca\/value\/\">#VALUE!<\/a><\/h3>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t\t\t\t<a href=\"https:\/\/salonforall.es\/ca\/manicura-hibrida-claresa\/\" rel=\"tag\">Manicura h\u00edbrida Claresa<\/a><span class=\"wd-meta-sep\">,<\/span> <a href=\"https:\/\/salonforall.es\/ca\/manicura-hibrida-claresa\/bases-y-tops-hibridos\/\" rel=\"tag\">Bases i tops h\u00edbrids<\/a>\t\t<\/div>\n\t\t\n\t\t\n\t\t<div class=\"wrap-price\">\n\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>5,89<span class=\"woocommerce-Price-currencySymbol\">\u20ac<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">El preu original era: 5,89&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>4,47<span class=\"woocommerce-Price-currencySymbol\">\u20ac<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">El preu actual \u00e9s: 4,47&euro;.<\/span> <small class=\"woocommerce-price-suffix\">IVA excl\u00f2s<\/small><\/span>\n\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t<div class=\"wd-product-footer\">\n\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t<a href=\"\/ca\/wp-json\/wp\/v2\/pages\/384?add-to-cart=13897\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_13897\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"13897\" data-product_sku=\"148385\" aria-label=\"Afegeix a la cistella: \u201c#VALUE!\u201d\" rel=\"nofollow\" data-success_message=\"\u201c#VALUE!\u201d s&#039;ha afegit a la vostra cistella\" role=\"button\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span class=\"wd-action-icon\"><span class=\"wd-check-icon\"><\/span><\/span><span class=\"wd-action-text\" data-no-translation=\"\" data-trp-gettext=\"\">Afegeix a la cistella<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_13897\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t<div class=\"wd-action-buttons\">\n\t\t\t\t\t\t<div class=\"wd-compare-btn wd-action-btn wd-style-icon wd-compare-icon wd-tooltip\">\n\t\t\t<a href=\"https:\/\/salonforall.es\/ca\/compare\/\" class=\"\" data-id=\"13897\" rel=\"nofollow\">\n\t\t\t\t<span class=\"wd-action-icon\">\n\t\t\t\t\t<span class=\"wd-check-icon\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class=\"wd-action-text\">Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-quick-view-btn wd-quick-view-icon wd-action-btn wd-style-icon wd-tooltip\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/salonforall.es\/ca\/value\/\"\n\t\t\t\tclass=\"open-quick-view\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"13897\"\n\t\t\t\t>\n\t\t\t\t\t<span class=\"wd-action-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">\n\t\t\t\t\t\tQuick view\t\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"wd-product wd-col wd-hover-buttons-on-hover product-grid-item product type-product post-4764 status-publish last instock product_cat-cosmetica-profesional product_cat-derma-roller product_tag-cosmetica-profesional product_tag-derma-roller has-post-thumbnail sale taxable shipping-taxable purchasable product-type-simple\" data-loop=\"3\" data-id=\"4764\">\n\t\n<div class=\"wd-product-wrapper product-wrapper\">\n\t<div class=\"wd-product-thumb product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/salonforall.es\/ca\/10-piezas-de-cartuchos-de-repuesto-para-el-boligrafo-de-microagujas-y-12-agujas\/\" class=\"wd-product-img-link product-image-link\" tabindex=\"-1\" aria-label=\"10 Peces de cartutxos de recanvi per al bol\u00edgraf de microagulles i 12 agulles\">\n\t\t\t\t\t\t<div class=\"product-labels labels-rounded\">\n\t\t\t\t<span class=\"onsale product-label wd-shape-round\">-19%<\/span>\t\t\t<\/div>\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/10-Piezas-De-Cartuchos-De-Repuesto-Para-El-Boligrafo-De-Microagujas-Y-12-Agujas-600x600.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"10 Peces de cartutxos de recanvi per al bol\u00edgraf de microagulles i 12 agulles\" srcset=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/10-Piezas-De-Cartuchos-De-Repuesto-Para-El-Boligrafo-De-Microagujas-Y-12-Agujas-600x600.jpg 600w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/10-Piezas-De-Cartuchos-De-Repuesto-Para-El-Boligrafo-De-Microagujas-Y-12-Agujas-300x300.jpg 300w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/10-Piezas-De-Cartuchos-De-Repuesto-Para-El-Boligrafo-De-Microagujas-Y-12-Agujas-150x150.jpg 150w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/10-Piezas-De-Cartuchos-De-Repuesto-Para-El-Boligrafo-De-Microagujas-Y-12-Agujas-768x768.jpg 768w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/10-Piezas-De-Cartuchos-De-Repuesto-Para-El-Boligrafo-De-Microagujas-Y-12-Agujas-12x12.jpg 12w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/10-Piezas-De-Cartuchos-De-Repuesto-Para-El-Boligrafo-De-Microagujas-Y-12-Agujas.jpg 800w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/salonforall.es\/ca\/wishlist\/\" data-key=\"ab8c0d4a71\" data-product-id=\"4764\" rel=\"nofollow\">\n\t\t\t\t\t<span class=\"wd-action-icon\">\n\t\t\t\t\t\t<span class=\"wd-check-icon\"><\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom\">\n\n\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/salonforall.es\/ca\/10-piezas-de-cartuchos-de-repuesto-para-el-boligrafo-de-microagujas-y-12-agujas\/\">10 Peces de cartutxos de recanvi per al bol\u00edgraf de microagulles i 12 agulles<\/a><\/h3>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t\t\t\t<a href=\"https:\/\/salonforall.es\/ca\/cosmetica-profesional\/\" rel=\"tag\">Cosm\u00e8tica professional<\/a><span class=\"wd-meta-sep\">,<\/span> <a href=\"https:\/\/salonforall.es\/ca\/cosmetica-profesional\/derma-roller\/\" rel=\"tag\">Derma Roller<\/a>\t\t<\/div>\n\t\t\n\t\t\n\t\t<div class=\"wrap-price\">\n\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>29,46<span class=\"woocommerce-Price-currencySymbol\">\u20ac<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">El preu original era: 29,46&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>23,98<span class=\"woocommerce-Price-currencySymbol\">\u20ac<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">El preu actual \u00e9s: 23,98&euro;.<\/span> <small class=\"woocommerce-price-suffix\">IVA excl\u00f2s<\/small><\/span>\n\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t<div class=\"wd-product-footer\">\n\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t<a href=\"\/ca\/wp-json\/wp\/v2\/pages\/384?add-to-cart=4764\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_4764\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"4764\" data-product_sku=\"125958\" aria-label=\"Afegeix a la cistella: \u201c10 Piezas De Cartuchos De Repuesto Para El Bol\u00edgrafo De Microagujas Y 12 Agujas\u201d\" rel=\"nofollow\" data-success_message=\"\u201c10 Piezas De Cartuchos De Repuesto Para El Bol\u00edgrafo De Microagujas Y 12 Agujas\u201d s&#039;ha afegit a la vostra cistella\" role=\"button\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span class=\"wd-action-icon\"><span class=\"wd-check-icon\"><\/span><\/span><span class=\"wd-action-text\" data-no-translation=\"\" data-trp-gettext=\"\">Afegeix a la cistella<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_4764\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t<div class=\"wd-action-buttons\">\n\t\t\t\t\t\t<div class=\"wd-compare-btn wd-action-btn wd-style-icon wd-compare-icon wd-tooltip\">\n\t\t\t<a href=\"https:\/\/salonforall.es\/ca\/compare\/\" class=\"\" data-id=\"4764\" rel=\"nofollow\">\n\t\t\t\t<span class=\"wd-action-icon\">\n\t\t\t\t\t<span class=\"wd-check-icon\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class=\"wd-action-text\">Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-quick-view-btn wd-quick-view-icon wd-action-btn wd-style-icon wd-tooltip\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/salonforall.es\/ca\/10-piezas-de-cartuchos-de-repuesto-para-el-boligrafo-de-microagujas-y-12-agujas\/\"\n\t\t\t\tclass=\"open-quick-view\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"4764\"\n\t\t\t\t>\n\t\t\t\t\t<span class=\"wd-action-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">\n\t\t\t\t\t\tQuick view\t\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"wd-product wd-col wd-hover-buttons-on-hover product-grid-item product type-product post-14526 status-publish first instock product_cat-value product_tag-value has-post-thumbnail sale taxable shipping-taxable purchasable product-type-simple\" data-loop=\"4\" data-id=\"14526\">\n\t\n<div class=\"wd-product-wrapper product-wrapper\">\n\t<div class=\"wd-product-thumb product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/salonforall.es\/ca\/100-palitos-de-madera-para-cuticulas-de-manicura-de-115-cm-ocho-nails\/\" class=\"wd-product-img-link product-image-link\" tabindex=\"-1\" aria-label=\"100 Palets De Fusta Per Cut\u00edcules De Manicura De 11,5 Cm Vuit Nails\">\n\t\t\t\t\t<div class=\"wd-product-grid-slider wd-fill wd-hide-lg\">\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails-600x600.jpg\" data-image-srcset=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails-600x600.jpg 600w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails-300x300.jpg 300w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails-1024x1024.jpg 1024w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails-150x150.jpg 150w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails-768x768.jpg 768w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails-12x12.jpg 12w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails.jpg 1200w\" data-image-id=\"0\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails-2-600x600.jpg\" data-image-srcset=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails-2-600x600.jpg 600w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails-2-300x300.jpg 300w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails-2-1024x1024.jpg 1024w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails-2-150x150.jpg 150w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails-2-768x768.jpg 768w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails-2-12x12.jpg 12w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails-2.jpg 1200w\" data-image-id=\"1\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails-4-600x600.jpg\" data-image-srcset=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails-4-600x600.jpg 600w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails-4-300x300.jpg 300w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails-4-1024x1024.jpg 1024w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails-4-150x150.jpg 150w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails-4-768x768.jpg 768w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails-4-12x12.jpg 12w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails-4.jpg 1200w\" data-image-id=\"2\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails-6-600x600.jpg\" data-image-srcset=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails-6-600x600.jpg 600w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails-6-300x300.jpg 300w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails-6-1024x1024.jpg 1024w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails-6-150x150.jpg 150w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails-6-768x768.jpg 768w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails-6-12x12.jpg 12w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails-6.jpg 1200w\" data-image-id=\"3\"><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-product-grid-slider-nav wd-fill wd-hide-md\">\n\t\t\t\t<div class=\"wd-prev\"><\/div>\n\t\t\t\t<div class=\"wd-next\"><\/div>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"product-labels labels-rounded\">\n\t\t\t\t<span class=\"onsale product-label wd-shape-round\">-24%<\/span>\t\t\t<\/div>\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails-600x600.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"100 Palets De Fusta Per Cut\u00edcules De Manicura De 11\" srcset=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails-600x600.jpg 600w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails-300x300.jpg 300w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails-1024x1024.jpg 1024w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails-150x150.jpg 150w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails-768x768.jpg 768w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails-12x12.jpg 12w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-115-Cm-Ocho-Nails.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/salonforall.es\/ca\/wishlist\/\" data-key=\"ab8c0d4a71\" data-product-id=\"14526\" rel=\"nofollow\">\n\t\t\t\t\t<span class=\"wd-action-icon\">\n\t\t\t\t\t\t<span class=\"wd-check-icon\"><\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom\">\n\n\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/salonforall.es\/ca\/100-palitos-de-madera-para-cuticulas-de-manicura-de-115-cm-ocho-nails\/\">100 Palets De Fusta Per Cut\u00edcules De Manicura De 11,5 Cm Vuit Nails<\/a><\/h3>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t\t\t\t<a href=\"https:\/\/salonforall.es\/ca\/value\/\" rel=\"tag\">#VALUE!<\/a>\t\t<\/div>\n\t\t\n\t\t\n\t\t<div class=\"wrap-price\">\n\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>2,03<span class=\"woocommerce-Price-currencySymbol\">\u20ac<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">El preu original era: 2,03&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>1,54<span class=\"woocommerce-Price-currencySymbol\">\u20ac<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">El preu actual \u00e9s: 1,54&euro;.<\/span> <small class=\"woocommerce-price-suffix\">IVA excl\u00f2s<\/small><\/span>\n\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t<div class=\"wd-product-footer\">\n\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t<a href=\"\/ca\/wp-json\/wp\/v2\/pages\/384?add-to-cart=14526\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_14526\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"14526\" data-product_sku=\"147357\" aria-label=\"Afegeix a la cistella: \u201c100 Palitos De Madera Para Cut\u00edculas De Manicura De 11,5 Cm Ocho Nails\u201d\" rel=\"nofollow\" data-success_message=\"\u201c100 Palitos De Madera Para Cut\u00edculas De Manicura De 11,5 Cm Ocho Nails\u201d s&#039;ha afegit a la vostra cistella\" role=\"button\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span class=\"wd-action-icon\"><span class=\"wd-check-icon\"><\/span><\/span><span class=\"wd-action-text\" data-no-translation=\"\" data-trp-gettext=\"\">Afegeix a la cistella<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_14526\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t<div class=\"wd-action-buttons\">\n\t\t\t\t\t\t<div class=\"wd-compare-btn wd-action-btn wd-style-icon wd-compare-icon wd-tooltip\">\n\t\t\t<a href=\"https:\/\/salonforall.es\/ca\/compare\/\" class=\"\" data-id=\"14526\" rel=\"nofollow\">\n\t\t\t\t<span class=\"wd-action-icon\">\n\t\t\t\t\t<span class=\"wd-check-icon\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class=\"wd-action-text\">Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-quick-view-btn wd-quick-view-icon wd-action-btn wd-style-icon wd-tooltip\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/salonforall.es\/ca\/100-palitos-de-madera-para-cuticulas-de-manicura-de-115-cm-ocho-nails\/\"\n\t\t\t\tclass=\"open-quick-view\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"14526\"\n\t\t\t\t>\n\t\t\t\t\t<span class=\"wd-action-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">\n\t\t\t\t\t\tQuick view\t\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"wd-product wd-col wd-hover-buttons-on-hover product-grid-item product type-product post-14531 status-publish instock product_cat-value product_tag-value has-post-thumbnail sale taxable shipping-taxable purchasable product-type-simple\" data-loop=\"5\" data-id=\"14531\">\n\t\n<div class=\"wd-product-wrapper product-wrapper\">\n\t<div class=\"wd-product-thumb product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/salonforall.es\/ca\/100-palitos-de-madera-para-cuticulas-de-manicura-de-15-cm-ocho-nails\/\" class=\"wd-product-img-link product-image-link\" tabindex=\"-1\" aria-label=\"100 Palets De Fusta Per Cut\u00edcules De Manicura De 15 Cm Vuit Nails\">\n\t\t\t\t\t<div class=\"wd-product-grid-slider wd-fill wd-hide-lg\">\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails-600x600.jpg\" data-image-srcset=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails-600x600.jpg 600w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails-300x300.jpg 300w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails-1024x1024.jpg 1024w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails-150x150.jpg 150w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails-768x768.jpg 768w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails-12x12.jpg 12w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails.jpg 1200w\" data-image-id=\"0\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails-2-600x600.jpg\" data-image-srcset=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails-2-600x600.jpg 600w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails-2-300x300.jpg 300w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails-2-1024x1024.jpg 1024w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails-2-150x150.jpg 150w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails-2-768x768.jpg 768w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails-2-12x12.jpg 12w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails-2.jpg 1200w\" data-image-id=\"1\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails-4-600x600.jpg\" data-image-srcset=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails-4-600x600.jpg 600w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails-4-300x300.jpg 300w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails-4-1024x1024.jpg 1024w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails-4-150x150.jpg 150w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails-4-768x768.jpg 768w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails-4-12x12.jpg 12w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails-4.jpg 1200w\" data-image-id=\"2\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails-6-600x600.jpg\" data-image-srcset=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails-6-600x600.jpg 600w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails-6-300x300.jpg 300w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails-6-1024x1024.jpg 1024w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails-6-150x150.jpg 150w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails-6-768x768.jpg 768w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails-6-12x12.jpg 12w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails-6.jpg 1200w\" data-image-id=\"3\"><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-product-grid-slider-nav wd-fill wd-hide-md\">\n\t\t\t\t<div class=\"wd-prev\"><\/div>\n\t\t\t\t<div class=\"wd-next\"><\/div>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"product-labels labels-rounded\">\n\t\t\t\t<span class=\"onsale product-label wd-shape-round\">-24%<\/span>\t\t\t<\/div>\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails-600x600.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"100 Palets De Fusta Per Cut\u00edcules De Manicura De 15 Cm Vuit Nails\" srcset=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails-600x600.jpg 600w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails-300x300.jpg 300w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails-1024x1024.jpg 1024w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails-150x150.jpg 150w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails-768x768.jpg 768w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails-12x12.jpg 12w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-15-Cm-Ocho-Nails.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/salonforall.es\/ca\/wishlist\/\" data-key=\"ab8c0d4a71\" data-product-id=\"14531\" rel=\"nofollow\">\n\t\t\t\t\t<span class=\"wd-action-icon\">\n\t\t\t\t\t\t<span class=\"wd-check-icon\"><\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom\">\n\n\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/salonforall.es\/ca\/100-palitos-de-madera-para-cuticulas-de-manicura-de-15-cm-ocho-nails\/\">100 Palets De Fusta Per Cut\u00edcules De Manicura De 15 Cm Vuit Nails<\/a><\/h3>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t\t\t\t<a href=\"https:\/\/salonforall.es\/ca\/value\/\" rel=\"tag\">#VALUE!<\/a>\t\t<\/div>\n\t\t\n\t\t\n\t\t<div class=\"wrap-price\">\n\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>2,73<span class=\"woocommerce-Price-currencySymbol\">\u20ac<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">El preu original era: 2,73&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>2,07<span class=\"woocommerce-Price-currencySymbol\">\u20ac<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">El preu actual \u00e9s: 2,07&euro;.<\/span> <small class=\"woocommerce-price-suffix\">IVA excl\u00f2s<\/small><\/span>\n\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t<div class=\"wd-product-footer\">\n\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t<a href=\"\/ca\/wp-json\/wp\/v2\/pages\/384?add-to-cart=14531\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_14531\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"14531\" data-product_sku=\"147358\" aria-label=\"Afegeix a la cistella: \u201c100 Palitos De Madera Para Cut\u00edculas De Manicura De 15 Cm Ocho Nails\u201d\" rel=\"nofollow\" data-success_message=\"\u201c100 Palitos De Madera Para Cut\u00edculas De Manicura De 15 Cm Ocho Nails\u201d s&#039;ha afegit a la vostra cistella\" role=\"button\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span class=\"wd-action-icon\"><span class=\"wd-check-icon\"><\/span><\/span><span class=\"wd-action-text\" data-no-translation=\"\" data-trp-gettext=\"\">Afegeix a la cistella<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_14531\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t<div class=\"wd-action-buttons\">\n\t\t\t\t\t\t<div class=\"wd-compare-btn wd-action-btn wd-style-icon wd-compare-icon wd-tooltip\">\n\t\t\t<a href=\"https:\/\/salonforall.es\/ca\/compare\/\" class=\"\" data-id=\"14531\" rel=\"nofollow\">\n\t\t\t\t<span class=\"wd-action-icon\">\n\t\t\t\t\t<span class=\"wd-check-icon\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class=\"wd-action-text\">Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-quick-view-btn wd-quick-view-icon wd-action-btn wd-style-icon wd-tooltip\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/salonforall.es\/ca\/100-palitos-de-madera-para-cuticulas-de-manicura-de-15-cm-ocho-nails\/\"\n\t\t\t\tclass=\"open-quick-view\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"14531\"\n\t\t\t\t>\n\t\t\t\t\t<span class=\"wd-action-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">\n\t\t\t\t\t\tQuick view\t\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"wd-product wd-col wd-hover-buttons-on-hover product-grid-item product type-product post-14521 status-publish instock product_cat-value product_tag-value has-post-thumbnail sale taxable shipping-taxable purchasable product-type-simple\" data-loop=\"6\" data-id=\"14521\">\n\t\n<div class=\"wd-product-wrapper product-wrapper\">\n\t<div class=\"wd-product-thumb product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/salonforall.es\/ca\/100-palitos-de-madera-para-cuticulas-de-manicura-de-65-cm-ocho-nails\/\" class=\"wd-product-img-link product-image-link\" tabindex=\"-1\" aria-label=\"100 Palets De Fusta Per Cut\u00edcules De Manicura De 6,5 Cm Vuit Nails\">\n\t\t\t\t\t<div class=\"wd-product-grid-slider wd-fill wd-hide-lg\">\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails-600x600.jpg\" data-image-srcset=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails-600x600.jpg 600w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails-300x300.jpg 300w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails-1024x1024.jpg 1024w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails-150x150.jpg 150w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails-768x768.jpg 768w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails-12x12.jpg 12w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails.jpg 1200w\" data-image-id=\"0\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails-2-600x600.jpg\" data-image-srcset=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails-2-600x600.jpg 600w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails-2-300x300.jpg 300w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails-2-1024x1024.jpg 1024w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails-2-150x150.jpg 150w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails-2-768x768.jpg 768w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails-2-12x12.jpg 12w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails-2.jpg 1200w\" data-image-id=\"1\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails-4-600x600.jpg\" data-image-srcset=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails-4-600x600.jpg 600w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails-4-300x300.jpg 300w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails-4-1024x1024.jpg 1024w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails-4-150x150.jpg 150w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails-4-768x768.jpg 768w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails-4-12x12.jpg 12w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails-4.jpg 1200w\" data-image-id=\"2\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails-6-600x600.jpg\" data-image-srcset=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails-6-600x600.jpg 600w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails-6-300x300.jpg 300w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails-6-1024x1024.jpg 1024w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails-6-150x150.jpg 150w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails-6-768x768.jpg 768w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails-6-12x12.jpg 12w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails-6.jpg 1200w\" data-image-id=\"3\"><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-product-grid-slider-nav wd-fill wd-hide-md\">\n\t\t\t\t<div class=\"wd-prev\"><\/div>\n\t\t\t\t<div class=\"wd-next\"><\/div>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"product-labels labels-rounded\">\n\t\t\t\t<span class=\"onsale product-label wd-shape-round\">-24%<\/span>\t\t\t<\/div>\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails-600x600.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"100 Palets De Fusta Per Cut\u00edcules De Manicura De 6\" srcset=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails-600x600.jpg 600w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails-300x300.jpg 300w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails-1024x1024.jpg 1024w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails-150x150.jpg 150w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails-768x768.jpg 768w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails-12x12.jpg 12w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/100-Palitos-De-Madera-Para-Cuticulas-De-Manicura-De-65-Cm-Ocho-Nails.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/salonforall.es\/ca\/wishlist\/\" data-key=\"ab8c0d4a71\" data-product-id=\"14521\" rel=\"nofollow\">\n\t\t\t\t\t<span class=\"wd-action-icon\">\n\t\t\t\t\t\t<span class=\"wd-check-icon\"><\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom\">\n\n\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/salonforall.es\/ca\/100-palitos-de-madera-para-cuticulas-de-manicura-de-65-cm-ocho-nails\/\">100 Palets De Fusta Per Cut\u00edcules De Manicura De 6,5 Cm Vuit Nails<\/a><\/h3>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t\t\t\t<a href=\"https:\/\/salonforall.es\/ca\/value\/\" rel=\"tag\">#VALUE!<\/a>\t\t<\/div>\n\t\t\n\t\t\n\t\t<div class=\"wrap-price\">\n\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>1,57<span class=\"woocommerce-Price-currencySymbol\">\u20ac<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">El preu original era: 1,57&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>1,19<span class=\"woocommerce-Price-currencySymbol\">\u20ac<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">El preu actual \u00e9s: 1,19&euro;.<\/span> <small class=\"woocommerce-price-suffix\">IVA excl\u00f2s<\/small><\/span>\n\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t<div class=\"wd-product-footer\">\n\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t<a href=\"\/ca\/wp-json\/wp\/v2\/pages\/384?add-to-cart=14521\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_14521\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"14521\" data-product_sku=\"147356\" aria-label=\"Afegeix a la cistella: \u201c100 Palitos De Madera Para Cut\u00edculas De Manicura De 6,5 Cm Ocho Nails\u201d\" rel=\"nofollow\" data-success_message=\"\u201c100 Palitos De Madera Para Cut\u00edculas De Manicura De 6,5 Cm Ocho Nails\u201d s&#039;ha afegit a la vostra cistella\" role=\"button\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span class=\"wd-action-icon\"><span class=\"wd-check-icon\"><\/span><\/span><span class=\"wd-action-text\" data-no-translation=\"\" data-trp-gettext=\"\">Afegeix a la cistella<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_14521\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t<div class=\"wd-action-buttons\">\n\t\t\t\t\t\t<div class=\"wd-compare-btn wd-action-btn wd-style-icon wd-compare-icon wd-tooltip\">\n\t\t\t<a href=\"https:\/\/salonforall.es\/ca\/compare\/\" class=\"\" data-id=\"14521\" rel=\"nofollow\">\n\t\t\t\t<span class=\"wd-action-icon\">\n\t\t\t\t\t<span class=\"wd-check-icon\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class=\"wd-action-text\">Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-quick-view-btn wd-quick-view-icon wd-action-btn wd-style-icon wd-tooltip\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/salonforall.es\/ca\/100-palitos-de-madera-para-cuticulas-de-manicura-de-65-cm-ocho-nails\/\"\n\t\t\t\tclass=\"open-quick-view\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"14521\"\n\t\t\t\t>\n\t\t\t\t\t<span class=\"wd-action-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">\n\t\t\t\t\t\tQuick view\t\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"wd-product wd-col wd-hover-buttons-on-hover product-grid-item product type-product post-249 status-publish last instock product_cat-chairs has-post-thumbnail sale taxable shipping-taxable purchasable product-type-simple\" data-loop=\"7\" data-id=\"249\">\n\t\n<div class=\"wd-product-wrapper product-wrapper\">\n\t<div class=\"wd-product-thumb product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/salonforall.es\/ca\/12-side\/\" class=\"wd-product-img-link product-image-link\" tabindex=\"-1\" aria-label=\"12 side\">\n\t\t\t\t\t<div class=\"wd-product-grid-slider wd-fill wd-hide-lg\">\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/salonforall.es\/wp-content\/uploads\/2023\/06\/wd-furniture-chair-prod-14-1-600x600.jpg\" data-image-srcset=\"\" data-image-id=\"0\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/salonforall.es\/wp-content\/uploads\/2023\/06\/wd-furniture-armchairs-prod-11-1-600x600.jpg\" data-image-srcset=\"\" data-image-id=\"1\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/salonforall.es\/wp-content\/uploads\/2023\/06\/wd-furniture-sofas-prod-4-5-600x600.jpg\" data-image-srcset=\"\" data-image-id=\"2\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/salonforall.es\/wp-content\/uploads\/2023\/06\/wd-furniture-armchairs-prod-15-1-600x600.jpg\" data-image-srcset=\"\" data-image-id=\"3\"><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-product-grid-slider-nav wd-fill wd-hide-md\">\n\t\t\t\t<div class=\"wd-prev\"><\/div>\n\t\t\t\t<div class=\"wd-next\"><\/div>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"product-labels labels-rounded\">\n\t\t\t\t<span class=\"onsale product-label wd-shape-round\">-10%<\/span>\t\t\t<\/div>\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/salonforall.es\/wp-content\/uploads\/2023\/06\/wd-furniture-chair-prod-14-1-600x600.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/salonforall.es\/ca\/wishlist\/\" data-key=\"ab8c0d4a71\" data-product-id=\"249\" rel=\"nofollow\">\n\t\t\t\t\t<span class=\"wd-action-icon\">\n\t\t\t\t\t\t<span class=\"wd-check-icon\"><\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom\">\n\n\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/salonforall.es\/ca\/12-side\/\">12 side<\/a><\/h3>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t\t\t\t<a href=\"https:\/\/salonforall.es\/ca\/chairs\/\" rel=\"tag\">Chairs<\/a>\t\t<\/div>\n\t\t\n\t\t\n\t\t<div class=\"wrap-price\">\n\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>375,00<span class=\"woocommerce-Price-currencySymbol\">\u20ac<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">El preu original era: 375,00&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>339,00<span class=\"woocommerce-Price-currencySymbol\">\u20ac<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">El preu actual \u00e9s: 339,00&euro;.<\/span> <small class=\"woocommerce-price-suffix\">IVA excl\u00f2s<\/small><\/span>\n\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t<div class=\"wd-product-footer\">\n\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t<a href=\"\/ca\/wp-json\/wp\/v2\/pages\/384?add-to-cart=249\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_249\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"249\" data-product_sku=\"CH-109\" aria-label=\"Afegeix a la cistella: \u201c12 side\u201d\" rel=\"nofollow\" data-success_message=\"\u201c12 side\u201d s&#039;ha afegit a la vostra cistella\" role=\"button\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span class=\"wd-action-icon\"><span class=\"wd-check-icon\"><\/span><\/span><span class=\"wd-action-text\" data-no-translation=\"\" data-trp-gettext=\"\">Afegeix a la cistella<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_249\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t<div class=\"wd-action-buttons\">\n\t\t\t\t\t\t<div class=\"wd-compare-btn wd-action-btn wd-style-icon wd-compare-icon wd-tooltip\">\n\t\t\t<a href=\"https:\/\/salonforall.es\/ca\/compare\/\" class=\"\" data-id=\"249\" rel=\"nofollow\">\n\t\t\t\t<span class=\"wd-action-icon\">\n\t\t\t\t\t<span class=\"wd-check-icon\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class=\"wd-action-text\">Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-quick-view-btn wd-quick-view-icon wd-action-btn wd-style-icon wd-tooltip\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/salonforall.es\/ca\/12-side\/\"\n\t\t\t\tclass=\"open-quick-view\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"249\"\n\t\t\t\t>\n\t\t\t\t\t<span class=\"wd-action-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">\n\t\t\t\t\t\tQuick view\t\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"wd-product wd-col wd-hover-buttons-on-hover product-grid-item product type-product post-9971 status-publish first instock product_cat-muebles-4rico product_tag-muebles-4rico has-post-thumbnail sale taxable shipping-taxable purchasable product-type-simple\" data-loop=\"8\" data-id=\"9971\">\n\t\n<div class=\"wd-product-wrapper product-wrapper\">\n\t<div class=\"wd-product-thumb product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/salonforall.es\/ca\/4rico-bar-hocker-qs-b16g-gris-terciopelo\/\" class=\"wd-product-img-link product-image-link\" tabindex=\"-1\" aria-label=\"4Rico Bar Hocker Qs-B16G Gris Vellut\">\n\t\t\t\t\t<div class=\"wd-product-grid-slider wd-fill wd-hide-lg\">\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-600x600.jpg\" data-image-srcset=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-600x600.jpg 600w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-300x300.jpg 300w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-1024x1024.jpg 1024w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-150x150.jpg 150w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-768x768.jpg 768w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-12x12.jpg 12w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo.jpg 1200w\" data-image-id=\"0\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-2-600x600.jpg\" data-image-srcset=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-2-600x600.jpg 600w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-2-300x300.jpg 300w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-2-1024x1024.jpg 1024w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-2-150x150.jpg 150w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-2-768x768.jpg 768w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-2-12x12.jpg 12w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-2.jpg 1200w\" data-image-id=\"1\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-4-600x600.jpg\" data-image-srcset=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-4-600x600.jpg 600w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-4-300x300.jpg 300w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-4-1024x1024.jpg 1024w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-4-150x150.jpg 150w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-4-768x768.jpg 768w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-4-12x12.jpg 12w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-4.jpg 1200w\" data-image-id=\"2\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-6-600x600.jpg\" data-image-srcset=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-6-600x600.jpg 600w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-6-300x300.jpg 300w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-6-1024x1024.jpg 1024w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-6-150x150.jpg 150w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-6-768x768.jpg 768w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-6-12x12.jpg 12w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-6.jpg 1200w\" data-image-id=\"3\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-8-600x600.jpg\" data-image-srcset=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-8-600x600.jpg 600w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-8-300x300.jpg 300w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-8-1024x1024.jpg 1024w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-8-150x150.jpg 150w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-8-768x768.jpg 768w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-8-12x12.jpg 12w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-8.jpg 1200w\" data-image-id=\"4\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-10-600x600.jpg\" data-image-srcset=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-10-600x600.jpg 600w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-10-300x300.jpg 300w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-10-1024x1024.jpg 1024w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-10-150x150.jpg 150w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-10-768x768.jpg 768w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-10-12x12.jpg 12w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-10.jpg 1200w\" data-image-id=\"5\"><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-product-grid-slider-nav wd-fill wd-hide-md\">\n\t\t\t\t<div class=\"wd-prev\"><\/div>\n\t\t\t\t<div class=\"wd-next\"><\/div>\n\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"product-labels labels-rounded\">\n\t\t\t\t<span class=\"onsale product-label wd-shape-round\">-19%<\/span>\t\t\t<\/div>\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-600x600.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"4Rico Bar Hocker Qs-B16G Gris Vellut\" srcset=\"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-600x600.jpg 600w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-300x300.jpg 300w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-1024x1024.jpg 1024w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-150x150.jpg 150w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-768x768.jpg 768w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo-12x12.jpg 12w, https:\/\/salonforall.es\/wp-content\/uploads\/2025\/12\/4Rico-Bar-Hocker-Qs-B16G-Gris-Terciopelo.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/salonforall.es\/ca\/wishlist\/\" data-key=\"ab8c0d4a71\" data-product-id=\"9971\" rel=\"nofollow\">\n\t\t\t\t\t<span class=\"wd-action-icon\">\n\t\t\t\t\t\t<span class=\"wd-check-icon\"><\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"product-element-bottom\">\n\n\t\t<div class=\"wd-product-header\">\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/salonforall.es\/ca\/4rico-bar-hocker-qs-b16g-gris-terciopelo\/\">4Rico Bar Hocker Qs-B16G Gris Vellut<\/a><\/h3>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t\t\t\t<a href=\"https:\/\/salonforall.es\/ca\/muebles-4rico\/\" rel=\"tag\">Mobles 4Rico<\/a>\t\t<\/div>\n\t\t\n\t\t\n\t\t<div class=\"wrap-price\">\n\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>110,21<span class=\"woocommerce-Price-currencySymbol\">\u20ac<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">El preu original era: 110,21&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>89,69<span class=\"woocommerce-Price-currencySymbol\">\u20ac<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">El preu actual \u00e9s: 89,69&euro;.<\/span> <small class=\"woocommerce-price-suffix\">IVA excl\u00f2s<\/small><\/span>\n\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\n\t\t\n\t\t<div class=\"wd-product-footer\">\n\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t<a href=\"\/ca\/wp-json\/wp\/v2\/pages\/384?add-to-cart=9971\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_9971\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"9971\" data-product_sku=\"141189\" aria-label=\"Afegeix a la cistella: \u201c4Rico Bar Hocker Qs-B16G Gris Terciopelo\u201d\" rel=\"nofollow\" data-success_message=\"\u201c4Rico Bar Hocker Qs-B16G Gris Terciopelo\u201d s&#039;ha afegit a la vostra cistella\" role=\"button\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span class=\"wd-action-icon\"><span class=\"wd-check-icon\"><\/span><\/span><span class=\"wd-action-text\" data-no-translation=\"\" data-trp-gettext=\"\">Afegeix a la cistella<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_9971\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t<div class=\"wd-action-buttons\">\n\t\t\t\t\t\t<div class=\"wd-compare-btn wd-action-btn wd-style-icon wd-compare-icon wd-tooltip\">\n\t\t\t<a href=\"https:\/\/salonforall.es\/ca\/compare\/\" class=\"\" data-id=\"9971\" rel=\"nofollow\">\n\t\t\t\t<span class=\"wd-action-icon\">\n\t\t\t\t\t<span class=\"wd-check-icon\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class=\"wd-action-text\">Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-quick-view-btn wd-quick-view-icon wd-action-btn wd-style-icon wd-tooltip\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/salonforall.es\/ca\/4rico-bar-hocker-qs-b16g-gris-terciopelo\/\"\n\t\t\t\tclass=\"open-quick-view\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"9971\"\n\t\t\t\t>\n\t\t\t\t\t<span class=\"wd-action-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">\n\t\t\t\t\t\tQuick view\t\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Informaci\u00f3n sobre 4Rico Bar Hocker Qs-B16G Gris Terciopelo con n\u00famero de art\u00edculo 141189 Los muebles de la marca 4Rico combinan","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-384","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Home Salon For All Espa\u00f1a - Salon For ALL Espa\u00f1a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/salonforall.es\/ca\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Home Salon For All Espa\u00f1a - Salon For ALL Espa\u00f1a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/salonforall.es\/ca\/\" \/>\n<meta property=\"og:site_name\" content=\"Salon For ALL Espa\u00f1a\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-09T13:32:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/\",\"url\":\"https:\\\/\\\/salonforall.es\\\/\",\"name\":\"Home Salon For All Espa\u00f1a - Salon For ALL Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/salonforall.es\\\/#website\"},\"datePublished\":\"2023-06-06T10:59:10+00:00\",\"dateModified\":\"2025-12-09T13:32:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/salonforall.es\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/salonforall.es\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/salonforall.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home Salon For All Espa\u00f1a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/#website\",\"url\":\"https:\\\/\\\/salonforall.es\\\/\",\"name\":\"Salon For ALL Espa\u00f1a\",\"description\":\"Mayorista de mobiliario y suministros para consultorios y salones\",\"publisher\":{\"@id\":\"https:\\\/\\\/salonforall.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/salonforall.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/#organization\",\"name\":\"Salon For All B.V. Espa\u00f1a\",\"alternateName\":\"Salon For All B.V. Espa\u00f1a - Mayorista de equipamiento para consultas, salones y suministros\",\"url\":\"https:\\\/\\\/salonforall.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/salonforall.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/salonforall.es\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-salon-for-all-e1764543185849.png\",\"contentUrl\":\"https:\\\/\\\/salonforall.es\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/logo-salon-for-all-e1764543185849.png\",\"width\":500,\"height\":150,\"caption\":\"Salon For All B.V. Espa\u00f1a\"},\"image\":{\"@id\":\"https:\\\/\\\/salonforall.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Home Salon For All Espanya - Salon For ALL Espanya","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/salonforall.es\/ca\/","og_locale":"ca_ES","og_type":"article","og_title":"Home Salon For All Espa\u00f1a - Salon For ALL Espa\u00f1a","og_url":"https:\/\/salonforall.es\/ca\/","og_site_name":"Salon For ALL Espa\u00f1a","article_modified_time":"2025-12-09T13:32:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/salonforall.es\/","url":"https:\/\/salonforall.es\/","name":"Home Salon For All Espanya - Salon For ALL Espanya","isPartOf":{"@id":"https:\/\/salonforall.es\/#website"},"datePublished":"2023-06-06T10:59:10+00:00","dateModified":"2025-12-09T13:32:37+00:00","breadcrumb":{"@id":"https:\/\/salonforall.es\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/salonforall.es\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/salonforall.es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/salonforall.es\/"},{"@type":"ListItem","position":2,"name":"Home Salon For All Espa\u00f1a"}]},{"@type":"WebSite","@id":"https:\/\/salonforall.es\/#website","url":"https:\/\/salonforall.es\/","name":"Salon For ALL Espanya","description":"Majorista de mobiliari i subministraments per a consultoris i salons","publisher":{"@id":"https:\/\/salonforall.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/salonforall.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/salonforall.es\/#organization","name":"Salon For All BV Espanya","alternateName":"Salon For All B.V. Espa\u00f1a - Mayorista de equipamiento para consultas, salones y suministros","url":"https:\/\/salonforall.es\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/salonforall.es\/#\/schema\/logo\/image\/","url":"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/11\/logo-salon-for-all-e1764543185849.png","contentUrl":"https:\/\/salonforall.es\/wp-content\/uploads\/2025\/11\/logo-salon-for-all-e1764543185849.png","width":500,"height":150,"caption":"Salon For All B.V. Espa\u00f1a"},"image":{"@id":"https:\/\/salonforall.es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/salonforall.es\/ca\/wp-json\/wp\/v2\/pages\/384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salonforall.es\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/salonforall.es\/ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/salonforall.es\/ca\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/salonforall.es\/ca\/wp-json\/wp\/v2\/comments?post=384"}],"version-history":[{"count":13,"href":"https:\/\/salonforall.es\/ca\/wp-json\/wp\/v2\/pages\/384\/revisions"}],"predecessor-version":[{"id":22509,"href":"https:\/\/salonforall.es\/ca\/wp-json\/wp\/v2\/pages\/384\/revisions\/22509"}],"wp:attachment":[{"href":"https:\/\/salonforall.es\/ca\/wp-json\/wp\/v2\/media?parent=384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}